{"id":9315,"date":"2026-01-10T14:35:48","date_gmt":"2026-01-10T06:35:48","guid":{"rendered":"https:\/\/jointopcap.com\/?page_id=9315"},"modified":"2026-03-11T09:17:44","modified_gmt":"2026-03-11T01:17:44","slug":"custom-baseball-cap","status":"publish","type":"page","link":"https:\/\/jointopcap.com\/sv\/custom-baseball-cap\/","title":{"rendered":"Custom Baseball Cap"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"9315\" class=\"elementor elementor-9315\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7f2b388 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7f2b388\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a5b1c36\" data-id=\"a5b1c36\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4d30884 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"4d30884\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e40c529\" data-id=\"e40c529\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8c40435 elementor-widget elementor-widget-heading\" data-id=\"8c40435\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Premier Custom Baseball Cap Manufacturer<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1b70e4 elementor-widget elementor-widget-text-editor\" data-id=\"e1b70e4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tOEM\/ODM Solutions for Brands, Wholesalers, and Corporate Promotions. Factory Direct Pricing with ISO9001 Quality Control.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f89e7a8 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"f89e7a8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ee0156f\" data-id=\"ee0156f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6acdcae elementor-align-left elementor-widget elementor-widget-button\" data-id=\"6acdcae\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjEwNjYxIiwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Get A Free Quote<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-27bb4d1\" data-id=\"27bb4d1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-248bce2 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"248bce2\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-download\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M216 0h80c13.3 0 24 10.7 24 24v168h87.7c17.8 0 26.7 21.5 14.1 34.1L269.7 378.3c-7.5 7.5-19.8 7.5-27.3 0L90.1 226.1c-12.6-12.6-3.7-34.1 14.1-34.1H192V24c0-13.3 10.7-24 24-24zm296 376v112c0 13.3-10.7 24-24 24H24c-13.3 0-24-10.7-24-24V376c0-13.3 10.7-24 24-24h146.7l49 49c20.1 20.1 52.5 20.1 72.6 0l49-49H488c13.3 0 24 10.7 24 24zm-124 88c0-11-9-20-20-20s-20 9-20 20 9 20 20 20 20-9 20-20zm64 0c0-11-9-20-20-20s-20 9-20 20 9 20 20 20 20-9 20-20z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Download Catalog<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8e4ad35\" data-id=\"8e4ad35\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7ce70ca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7ce70ca\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b6a246c\" data-id=\"b6a246c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a20f54f elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"a20f54f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-147dfc9\" data-id=\"147dfc9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0cd4ec4 elementor-view-stacked elementor-position-left elementor-tablet-position-left elementor-shape-circle elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"0cd4ec4\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-cog\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M487.4 315.7l-42.6-24.6c4.3-23.2 4.3-47 0-70.2l42.6-24.6c4.9-2.8 7.1-8.6 5.5-14-11.1-35.6-30-67.8-54.7-94.6-3.8-4.1-10-5.1-14.8-2.3L380.8 110c-17.9-15.4-38.5-27.3-60.8-35.1V25.8c0-5.6-3.9-10.5-9.4-11.7-36.7-8.2-74.3-7.8-109.2 0-5.5 1.2-9.4 6.1-9.4 11.7V75c-22.2 7.9-42.8 19.8-60.8 35.1L88.7 85.5c-4.9-2.8-11-1.9-14.8 2.3-24.7 26.7-43.6 58.9-54.7 94.6-1.7 5.4.6 11.2 5.5 14L67.3 221c-4.3 23.2-4.3 47 0 70.2l-42.6 24.6c-4.9 2.8-7.1 8.6-5.5 14 11.1 35.6 30 67.8 54.7 94.6 3.8 4.1 10 5.1 14.8 2.3l42.6-24.6c17.9 15.4 38.5 27.3 60.8 35.1v49.2c0 5.6 3.9 10.5 9.4 11.7 36.7 8.2 74.3 7.8 109.2 0 5.5-1.2 9.4-6.1 9.4-11.7v-49.2c22.2-7.9 42.8-19.8 60.8-35.1l42.6 24.6c4.9 2.8 11 1.9 14.8-2.3 24.7-26.7 43.6-58.9 54.7-94.6 1.5-5.5-.7-11.3-5.6-14.1zM256 336c-44.1 0-80-35.9-80-80s35.9-80 80-80 80 35.9 80 80-35.9 80-80 80z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tOEM\/ODM Expert\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t15+ years manufacturing experience.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-eb1e7dd\" data-id=\"eb1e7dd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-abd56c8 elementor-view-stacked elementor-position-left elementor-shape-circle elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"abd56c8\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-dollar-sign\" viewbox=\"0 0 288 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M209.2 233.4l-108-31.6C88.7 198.2 80 186.5 80 173.5c0-16.3 13.2-29.5 29.5-29.5h66.3c12.2 0 24.2 3.7 34.2 10.5 6.1 4.1 14.3 3.1 19.5-2l34.8-34c7.1-6.9 6.1-18.4-1.8-24.5C238 74.8 207.4 64.1 176 64V16c0-8.8-7.2-16-16-16h-32c-8.8 0-16 7.2-16 16v48h-2.5C45.8 64-5.4 118.7.5 183.6c4.2 46.1 39.4 83.6 83.8 96.6l102.5 30c12.5 3.7 21.2 15.3 21.2 28.3 0 16.3-13.2 29.5-29.5 29.5h-66.3C100 368 88 364.3 78 357.5c-6.1-4.1-14.3-3.1-19.5 2l-34.8 34c-7.1 6.9-6.1 18.4 1.8 24.5 24.5 19.2 55.1 29.9 86.5 30v48c0 8.8 7.2 16 16 16h32c8.8 0 16-7.2 16-16v-48.2c46.6-.9 90.3-28.6 105.7-72.7 21.5-61.6-14.6-124.8-72.5-141.7z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tFactory Price\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDirect pricing, no middleman markup.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-af8cc8e\" data-id=\"af8cc8e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f1c135c elementor-view-stacked elementor-position-left elementor-shape-circle elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"f1c135c\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-cut\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M278.06 256L444.48 89.57c4.69-4.69 4.69-12.29 0-16.97-32.8-32.8-85.99-32.8-118.79 0L210.18 188.12l-24.86-24.86c4.31-10.92 6.68-22.81 6.68-35.26 0-53.02-42.98-96-96-96S0 74.98 0 128s42.98 96 96 96c4.54 0 8.99-.32 13.36-.93L142.29 256l-32.93 32.93c-4.37-.61-8.83-.93-13.36-.93-53.02 0-96 42.98-96 96s42.98 96 96 96 96-42.98 96-96c0-12.45-2.37-24.34-6.68-35.26l24.86-24.86L325.69 439.4c32.8 32.8 85.99 32.8 118.79 0 4.69-4.68 4.69-12.28 0-16.97L278.06 256zM96 160c-17.64 0-32-14.36-32-32s14.36-32 32-32 32 14.36 32 32-14.36 32-32 32zm0 256c-17.64 0-32-14.36-32-32s14.36-32 32-32 32 14.36 32 32-14.36 32-32 32z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t100% Custom\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tFully bespoke designs from scratch.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-ffb5df1\" data-id=\"ffb5df1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-07cc565 elementor-view-stacked elementor-position-left elementor-shape-circle elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"07cc565\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-box\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M509.5 184.6L458.9 32.8C452.4 13.2 434.1 0 413.4 0H272v192h238.7c-.4-2.5-.4-5-1.2-7.4zM240 0H98.6c-20.7 0-39 13.2-45.5 32.8L2.5 184.6c-.8 2.4-.8 4.9-1.2 7.4H240V0zM0 224v240c0 26.5 21.5 48 48 48h416c26.5 0 48-21.5 48-48V224H0z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tLow MOQ\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tStart small with 50pcs per style.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-384c423 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"384c423\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4557047\" data-id=\"4557047\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-450bcc5 elementor-widget elementor-widget-heading\" data-id=\"450bcc5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Trusted By 500+ Brands WorldWide<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57d654b elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"57d654b\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;6&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;slides_to_show_tablet&quot;:&quot;4&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 di 6\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/kerusso.png\" alt=\"#image_title\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 di 6\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/good-good-golf.jpg\" alt=\"#image_title\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 di 6\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Captain-Fin-scaled-1.png\" alt=\"#image_title\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 di 6\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/billabong.png\" alt=\"#image_title\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 di 6\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Bad-Birdie.png\" alt=\"#image_title\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 di 6\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/BB.png\" alt=\"#image_title\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-98dc761 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"98dc761\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-aca588e\" data-id=\"aca588e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5785fca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5785fca\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-c40a549\" data-id=\"c40a549\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d4ea26 elementor-widget elementor-widget-heading\" data-id=\"6d4ea26\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Custom Baseball Cap Styles<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1a05ac elementor-widget elementor-widget-text-editor\" data-id=\"e1a05ac\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tExplore our range of fully customizable hat profiles. From structured snapbacks to relaxed\ndad hats, we manufacture to your exact specifications.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-dc816ca elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"dc816ca\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ec71181\" data-id=\"ec71181\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"woocommerce elementor-element elementor-element-a645416 elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-widget elementor-widget-loop-grid\" data-id=\"a645416\" data-element_type=\"widget\" data-settings=\"{&quot;template_id&quot;:9555,&quot;_skin&quot;:&quot;product&quot;,&quot;columns&quot;:&quot;3&quot;,&quot;columns_tablet&quot;:&quot;2&quot;,&quot;columns_mobile&quot;:&quot;1&quot;,&quot;edit_handle_selector&quot;:&quot;[data-elementor-type=\\&quot;loop-item\\&quot;]&quot;,&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"loop-grid.product\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-loop-container elementor-grid\" role=\"list\">\n\t\t<style id=\"loop-9555\">.elementor-9555 .elementor-element.elementor-element-fdd4789{padding:0px 0px 0px 0px;}.elementor-9555 .elementor-element.elementor-element-e642aab > .elementor-widget-wrap > .elementor-widget:not(.elementor-widget__width-auto):not(.elementor-widget__width-initial):not(:last-child):not(.elementor-absolute){margin-bottom:0px;}.elementor-9555 .elementor-element.elementor-element-e642aab > .elementor-element-populated{border-style:solid;border-width:1px 1px 1px 1px;border-color:#F7F7F79C;box-shadow:0px 0px 10px 0px rgba(197.00000000000003, 197.00000000000003, 197.00000000000003, 0.22);transition:background 0.3s, border 0.5s, border-radius 0.5s, box-shadow 0.5s;padding:0px 0px 0px 0px;}.elementor-9555 .elementor-element.elementor-element-e642aab > .elementor-element-populated, .elementor-9555 .elementor-element.elementor-element-e642aab > .elementor-element-populated > .elementor-background-overlay, .elementor-9555 .elementor-element.elementor-element-e642aab > .elementor-background-slideshow{border-radius:10px 10px 10px 10px;}.elementor-9555 .elementor-element.elementor-element-e642aab:hover > .elementor-element-populated{border-style:solid;border-width:1px 1px 1px 1px;border-color:#C5C5C594;box-shadow:0px 5px 10px 3px rgba(197.00000000000003, 197.00000000000003, 197.00000000000003, 0.58);}.elementor-9555 .elementor-element.elementor-element-e642aab:hover > .elementor-element-populated, .elementor-9555 .elementor-element.elementor-element-e642aab:hover > .elementor-element-populated > .elementor-background-overlay{border-radius:10px 10px 10px 10px;}.elementor-9555 .elementor-element.elementor-element-e642aab > .elementor-element-populated > .elementor-background-overlay{transition:background 0.3s, border-radius 0.5s, opacity 0.3s;}.elementor-9555 .elementor-element.elementor-element-cc9639b img{transition-duration:0.5s;border-radius:10px 10px 0px 0px;}.elementor-9555 .elementor-element.elementor-element-e579e85{width:var( --container-widget-width, 23% );max-width:23%;--container-widget-width:23%;--container-widget-flex-grow:0;top:6px;text-align:center;font-family:\"Roboto Flex\", Sans-serif;font-size:14px;font-weight:600;color:#FFFFFF;}.elementor-9555 .elementor-element.elementor-element-e579e85 > .elementor-widget-container{background-color:#229488;margin:0px 0px 0px 0px;border-radius:3px 3px 3px 3px;}body:not(.rtl) .elementor-9555 .elementor-element.elementor-element-e579e85{right:6px;}body.rtl .elementor-9555 .elementor-element.elementor-element-e579e85{left:6px;}.elementor-9555 .elementor-element.elementor-element-99a19aa:not(.elementor-motion-effects-element-type-background), .elementor-9555 .elementor-element.elementor-element-99a19aa > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:#FFFFFF;}.elementor-9555 .elementor-element.elementor-element-99a19aa, .elementor-9555 .elementor-element.elementor-element-99a19aa > .elementor-background-overlay{border-radius:0px 0px 0px 0px;}.elementor-9555 .elementor-element.elementor-element-99a19aa{transition:background 0.3s, border 0.4s, border-radius 0.4s, box-shadow 0.4s;padding:10px 10px 0px 10px;}.elementor-9555 .elementor-element.elementor-element-99a19aa > .elementor-background-overlay{transition:background 0.3s, border-radius 0.4s, opacity 0.3s;}.elementor-bc-flex-widget .elementor-9555 .elementor-element.elementor-element-228aac0.elementor-column .elementor-widget-wrap{align-items:center;}.elementor-9555 .elementor-element.elementor-element-228aac0.elementor-column.elementor-element[data-element_type=\"column\"] > .elementor-widget-wrap.elementor-element-populated{align-content:center;align-items:center;}.elementor-9555 .elementor-element.elementor-element-30eb8c4{text-align:left;}.elementor-9555 .elementor-element.elementor-element-30eb8c4 .elementor-heading-title{font-family:\"Roboto Flex\", Sans-serif;font-size:20px;font-weight:700;line-height:26px;}.elementor-9555 .elementor-element.elementor-element-63a52e7 > .elementor-element-populated{padding:20px 0px 0px 0px;}.elementor-9555 .elementor-element.elementor-element-bd7eec9 .elementor-icon-list-icon{width:14px;}.elementor-9555 .elementor-element.elementor-element-bd7eec9 .elementor-icon-list-icon i{font-size:14px;}.elementor-9555 .elementor-element.elementor-element-bd7eec9 .elementor-icon-list-icon svg{--e-icon-list-icon-size:14px;}.elementor-9555 .elementor-element.elementor-element-bd7eec9 .elementor-icon-list-item{font-family:\"Roboto Flex\", Sans-serif;font-size:8px;font-weight:300;text-transform:none;font-style:normal;}.elementor-9555 .elementor-element.elementor-element-b398de8:not(.elementor-motion-effects-element-type-background), .elementor-9555 .elementor-element.elementor-element-b398de8 > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:#FFFFFF;}.elementor-9555 .elementor-element.elementor-element-b398de8, .elementor-9555 .elementor-element.elementor-element-b398de8 > .elementor-background-overlay{border-radius:0px 0px 0px 0px;}.elementor-9555 .elementor-element.elementor-element-b398de8{transition:background 0.3s, border 0.4s, border-radius 0.4s, box-shadow 0.4s;padding:10px 10px 0px 10px;}.elementor-9555 .elementor-element.elementor-element-b398de8 > .elementor-background-overlay{transition:background 0.3s, border-radius 0.4s, opacity 0.3s;}.elementor-9555 .elementor-element.elementor-element-0711a71{text-align:left;color:#525252;font-family:\"Roboto Flex\", Sans-serif;font-size:14px;font-weight:400;text-transform:none;font-style:normal;line-height:22px;}.elementor-9555 .elementor-element.elementor-element-161d34e:not(.elementor-motion-effects-element-type-background), .elementor-9555 .elementor-element.elementor-element-161d34e > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:#FFFFFF;}.elementor-9555 .elementor-element.elementor-element-161d34e, .elementor-9555 .elementor-element.elementor-element-161d34e > .elementor-background-overlay{border-radius:10px 10px 10px 10px;}.elementor-9555 .elementor-element.elementor-element-161d34e{transition:background 0.3s, border 0.4s, border-radius 0.4s, box-shadow 0.4s;padding:10px 10px 10px 10px;}.elementor-9555 .elementor-element.elementor-element-161d34e > .elementor-background-overlay{transition:background 0.3s, border-radius 0.4s, opacity 0.3s;}.elementor-9555 .elementor-element.elementor-element-c7d5abb .elementor-button{background-color:#0E766E00;font-family:\"Roboto Flex\", Sans-serif;font-size:16px;fill:#229488;color:#229488;transition-duration:0.4s;border-style:solid;border-width:1px 1px 1px 1px;border-color:#0E766E;border-radius:5px 5px 5px 5px;padding:12px 20px 12px 20px;}.elementor-9555 .elementor-element.elementor-element-c7d5abb .elementor-button:hover, .elementor-9555 .elementor-element.elementor-element-c7d5abb .elementor-button:focus{background-color:#0F766E0D;border-color:#115E59;}.elementor-9555 .elementor-element.elementor-element-c7d5abb .elementor-button .elementor-button-content-wrapper{justify-content:center;}@media(max-width:767px){.elementor-9555 .elementor-element.elementor-element-99a19aa{padding:0px 0px 0px 0px;}.elementor-9555 .elementor-element.elementor-element-228aac0 > .elementor-element-populated{padding:10px 10px 5px 10px;}.elementor-9555 .elementor-element.elementor-element-63a52e7 > .elementor-element-populated{padding:10px 11px 5px 15px;}.elementor-9555 .elementor-element.elementor-element-bd7eec9 .elementor-icon-list-item{font-size:10px;}.elementor-9555 .elementor-element.elementor-element-6897566{width:100%;}}@media(min-width:768px){.elementor-9555 .elementor-element.elementor-element-228aac0{width:75%;}.elementor-9555 .elementor-element.elementor-element-63a52e7{width:25%;}}@media(max-width:1024px) and (min-width:768px){.elementor-9555 .elementor-element.elementor-element-228aac0{width:100%;}.elementor-9555 .elementor-element.elementor-element-63a52e7{width:100%;}}\/* Start custom CSS for theme-post-title, class: .elementor-element-30eb8c4 *\/.pt-h3 h3.elementor-heading-title.elementor-size-default {\r\n    height: 50px;\r\n}\r\n\r\n@media(max-width:767px)\r\n{\r\n    .pt-h3 h3.elementor-heading-title.elementor-size-default {\r\n    height: 100%;\r\n}\r\n}\/* End custom CSS *\/\n\/* Start custom CSS for theme-post-content, class: .elementor-element-0711a71 *\/.new ul {\r\n    margin: 0px 0px 0px -23px;\r\n}\/* End custom CSS *\/\n\/* Start custom CSS for column, class: .elementor-element-e642aab *\/.elementor-column.elementor-col-100.elementor-top-column.elementor-element.elementor-element-e642aab.l-col{\n    overflow: hidden;\n}\/* End custom CSS *\/<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"9555\" class=\"elementor elementor-9555 e-loop-item e-loop-item-9539 post-9539 product type-product status-publish has-post-thumbnail product_cat-oem-odm product_tag-oem-odm first outofstock shipping-taxable product-type-simple\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fdd4789 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fdd4789\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e642aab l-col\" data-id=\"e642aab\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc9639b elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"cc9639b\" data-element_type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1500\" height=\"1500\" src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/1-removebg-preview.png\" class=\"attachment-full size-full wp-image-3468\" alt=\"\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/1-removebg-preview.png 1500w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/1-removebg-preview-300x300.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/1-removebg-preview-100x100.png 100w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/1-removebg-preview-600x600.png 600w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/1-removebg-preview-1024x1024.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/1-removebg-preview-150x150.png 150w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/1-removebg-preview-768x768.png 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e579e85 elementor-widget__width-initial elementor-absolute elementor-widget elementor-widget-text-editor\" data-id=\"e579e85\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tOEM\/ODM\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-99a19aa elementor-section-full_width sec elementor-section-height-default elementor-section-height-default\" data-id=\"99a19aa\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-228aac0\" data-id=\"228aac0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30eb8c4 pt-h3 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"30eb8c4\" data-element_type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Classic 6-Panel Dad Hat<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-63a52e7\" data-id=\"63a52e7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd7eec9 elementor-mobile-align-left elementor-widget elementor-widget-post-info\" data-id=\"bd7eec9\" data-element_type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-inline-items elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-88d16c9 elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-custom\">\n\t\t\t\t\t\t\t\t\t\tJC-DH-001\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b398de8 elementor-section-full_width sec elementor-section-height-default elementor-section-height-default\" data-id=\"b398de8\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6897566\" data-id=\"6897566\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0711a71 new elementor-widget elementor-widget-theme-post-content\" data-id=\"0711a71\" data-element_type=\"widget\" data-widget_type=\"theme-post-content.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"text-sm text-brand-700 font-medium mb-4\">MOQ:\u00a050 pcs\/design<\/p>\n<ul>\n<li class=\"mb-6\" style=\"text-align: left;\">Unstructured Cotton<\/li>\n<li class=\"mb-6\" style=\"text-align: left;\">Antique Brass Buckle<\/li>\n<li class=\"mb-6\" style=\"text-align: left;\">Curved Visor<\/li>\n<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-161d34e elementor-section-full_width sec elementor-section-height-default elementor-section-height-default\" data-id=\"161d34e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2e296ce\" data-id=\"2e296ce\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c7d5abb elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"c7d5abb\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjEwNjYxIiwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Request Quote<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"9555\" class=\"elementor elementor-9555 e-loop-item e-loop-item-9779 post-9779 product type-product status-publish has-post-thumbnail product_cat-oem-odm  instock shipping-taxable product-type-simple\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fdd4789 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fdd4789\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e642aab l-col\" data-id=\"e642aab\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc9639b elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"cc9639b\" data-element_type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1500\" height=\"1500\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/61dtpyqnjL._AC_SX569_.png\" class=\"attachment-full size-full wp-image-3646 lazyload\" alt=\"\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/61dtpyqnjL._AC_SX569_.png 1500w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/61dtpyqnjL._AC_SX569_-300x300.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/61dtpyqnjL._AC_SX569_-100x100.png 100w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/61dtpyqnjL._AC_SX569_-600x600.png 600w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/61dtpyqnjL._AC_SX569_-1024x1024.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/61dtpyqnjL._AC_SX569_-150x150.png 150w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/61dtpyqnjL._AC_SX569_-768x768.png 768w\" data-sizes=\"(max-width: 1500px) 100vw, 1500px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1500px; --smush-placeholder-aspect-ratio: 1500\/1500;\" \/><noscript><img decoding=\"async\" width=\"1500\" height=\"1500\" src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/61dtpyqnjL._AC_SX569_.png\" class=\"attachment-full size-full wp-image-3646\" alt=\"\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/61dtpyqnjL._AC_SX569_.png 1500w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/61dtpyqnjL._AC_SX569_-300x300.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/61dtpyqnjL._AC_SX569_-100x100.png 100w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/61dtpyqnjL._AC_SX569_-600x600.png 600w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/61dtpyqnjL._AC_SX569_-1024x1024.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/61dtpyqnjL._AC_SX569_-150x150.png 150w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/61dtpyqnjL._AC_SX569_-768x768.png 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e579e85 elementor-widget__width-initial elementor-absolute elementor-widget elementor-widget-text-editor\" data-id=\"e579e85\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tOEM\/ODM\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-99a19aa elementor-section-full_width sec elementor-section-height-default elementor-section-height-default\" data-id=\"99a19aa\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-228aac0\" data-id=\"228aac0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30eb8c4 pt-h3 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"30eb8c4\" data-element_type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Premium 3D Embroidery Snapback<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-63a52e7\" data-id=\"63a52e7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd7eec9 elementor-mobile-align-left elementor-widget elementor-widget-post-info\" data-id=\"bd7eec9\" data-element_type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-inline-items elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-88d16c9 elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-custom\">\n\t\t\t\t\t\t\t\t\t\tJC-SB-3D\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b398de8 elementor-section-full_width sec elementor-section-height-default elementor-section-height-default\" data-id=\"b398de8\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6897566\" data-id=\"6897566\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0711a71 new elementor-widget elementor-widget-theme-post-content\" data-id=\"0711a71\" data-element_type=\"widget\" data-widget_type=\"theme-post-content.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"text-sm text-brand-700 font-medium mb-4\">MOQ:\u00a0100 pcs\/design<\/p>\n<div class=\"mb-6\">\n<ul class=\"text-sm text-gray-600 space-y-1\">\n<li class=\"flex items-center\">Acrylic\/Wool Blend<\/li>\n<li class=\"flex items-center\">Flat Brim<\/li>\n<li class=\"flex items-center\">Plastic Snap Closure<\/li>\n<\/ul>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-161d34e elementor-section-full_width sec elementor-section-height-default elementor-section-height-default\" data-id=\"161d34e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2e296ce\" data-id=\"2e296ce\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c7d5abb elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"c7d5abb\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjEwNjYxIiwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Request Quote<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"9555\" class=\"elementor elementor-9555 e-loop-item e-loop-item-9793 post-9793 product type-product status-publish has-post-thumbnail product_cat-oem-odm  instock shipping-taxable product-type-simple\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fdd4789 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fdd4789\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e642aab l-col\" data-id=\"e642aab\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc9639b elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"cc9639b\" data-element_type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1280\" height=\"1280\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/image_5-Photoroom.png\" class=\"attachment-full size-full wp-image-3967 lazyload\" alt=\"\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/image_5-Photoroom.png 1280w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/image_5-Photoroom-300x300.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/image_5-Photoroom-100x100.png 100w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/image_5-Photoroom-600x600.png 600w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/image_5-Photoroom-1024x1024.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/image_5-Photoroom-150x150.png 150w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/image_5-Photoroom-768x768.png 768w\" data-sizes=\"(max-width: 1280px) 100vw, 1280px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1280px; --smush-placeholder-aspect-ratio: 1280\/1280;\" \/><noscript><img decoding=\"async\" width=\"1280\" height=\"1280\" src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/image_5-Photoroom.png\" class=\"attachment-full size-full wp-image-3967\" alt=\"\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/image_5-Photoroom.png 1280w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/image_5-Photoroom-300x300.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/image_5-Photoroom-100x100.png 100w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/image_5-Photoroom-600x600.png 600w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/image_5-Photoroom-1024x1024.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/image_5-Photoroom-150x150.png 150w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/image_5-Photoroom-768x768.png 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e579e85 elementor-widget__width-initial elementor-absolute elementor-widget elementor-widget-text-editor\" data-id=\"e579e85\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tOEM\/ODM\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-99a19aa elementor-section-full_width sec elementor-section-height-default elementor-section-height-default\" data-id=\"99a19aa\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-228aac0\" data-id=\"228aac0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30eb8c4 pt-h3 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"30eb8c4\" data-element_type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Vintage Washed Trucker Cap<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-63a52e7\" data-id=\"63a52e7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd7eec9 elementor-mobile-align-left elementor-widget elementor-widget-post-info\" data-id=\"bd7eec9\" data-element_type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-inline-items elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-88d16c9 elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-custom\">\n\t\t\t\t\t\t\t\t\t\tJC-TR-WSH\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b398de8 elementor-section-full_width sec elementor-section-height-default elementor-section-height-default\" data-id=\"b398de8\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6897566\" data-id=\"6897566\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0711a71 new elementor-widget elementor-widget-theme-post-content\" data-id=\"0711a71\" data-element_type=\"widget\" data-widget_type=\"theme-post-content.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"text-sm text-brand-700 font-medium mb-4\">MOQ:\u00a050 pcs\/design<\/p>\n<div class=\"mb-6\">\n<ul class=\"text-sm text-gray-600 space-y-1\">\n<li class=\"flex items-center\">Soft Mesh Back<\/li>\n<li class=\"flex items-center\">Distressed Cotton Front<\/li>\n<li class=\"flex items-center\">Low Profile<\/li>\n<\/ul>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-161d34e elementor-section-full_width sec elementor-section-height-default elementor-section-height-default\" data-id=\"161d34e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2e296ce\" data-id=\"2e296ce\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c7d5abb elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"c7d5abb\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjEwNjYxIiwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Request Quote<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"9555\" class=\"elementor elementor-9555 e-loop-item e-loop-item-9795 post-9795 product type-product status-publish has-post-thumbnail product_cat-oem-odm last instock shipping-taxable product-type-simple\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fdd4789 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fdd4789\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e642aab l-col\" data-id=\"e642aab\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc9639b elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"cc9639b\" data-element_type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"2560\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/08\/1-24-scaled.png\" class=\"attachment-full size-full wp-image-4667 lazyload\" alt=\"\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/08\/1-24-scaled.png 2560w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/08\/1-24-300x300.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/08\/1-24-100x100.png 100w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/08\/1-24-600x600.png 600w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/08\/1-24-1024x1024.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/08\/1-24-150x150.png 150w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/08\/1-24-768x768.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/08\/1-24-1536x1536.png 1536w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/08\/1-24-2048x2048.png 2048w\" data-sizes=\"(max-width: 2560px) 100vw, 2560px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 2560px; --smush-placeholder-aspect-ratio: 2560\/2560;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"2560\" src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/08\/1-24-scaled.png\" class=\"attachment-full size-full wp-image-4667\" alt=\"\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/08\/1-24-scaled.png 2560w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/08\/1-24-300x300.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/08\/1-24-100x100.png 100w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/08\/1-24-600x600.png 600w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/08\/1-24-1024x1024.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/08\/1-24-150x150.png 150w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/08\/1-24-768x768.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/08\/1-24-1536x1536.png 1536w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/08\/1-24-2048x2048.png 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e579e85 elementor-widget__width-initial elementor-absolute elementor-widget elementor-widget-text-editor\" data-id=\"e579e85\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tOEM\/ODM\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-99a19aa elementor-section-full_width sec elementor-section-height-default elementor-section-height-default\" data-id=\"99a19aa\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-228aac0\" data-id=\"228aac0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30eb8c4 pt-h3 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"30eb8c4\" data-element_type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Performance Laser Cut Cap<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-63a52e7\" data-id=\"63a52e7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd7eec9 elementor-mobile-align-left elementor-widget elementor-widget-post-info\" data-id=\"bd7eec9\" data-element_type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-inline-items elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-88d16c9 elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-custom\">\n\t\t\t\t\t\t\t\t\t\tJC-PF-LASER\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b398de8 elementor-section-full_width sec elementor-section-height-default elementor-section-height-default\" data-id=\"b398de8\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6897566\" data-id=\"6897566\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0711a71 new elementor-widget elementor-widget-theme-post-content\" data-id=\"0711a71\" data-element_type=\"widget\" data-widget_type=\"theme-post-content.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"text-sm text-brand-700 font-medium mb-4\">MOQ:\u00a0200 pcs\/design<\/p>\n<div class=\"mb-6\">\n<ul class=\"text-sm text-gray-600 space-y-1\">\n<li class=\"flex items-center\">Water Resistant<\/li>\n<li class=\"flex items-center\">Laser Perforated<\/li>\n<li class=\"flex items-center\">Seamless Bonding<\/li>\n<\/ul>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-161d34e elementor-section-full_width sec elementor-section-height-default elementor-section-height-default\" data-id=\"161d34e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2e296ce\" data-id=\"2e296ce\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c7d5abb elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"c7d5abb\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjEwNjYxIiwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Request Quote<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"9555\" class=\"elementor elementor-9555 e-loop-item e-loop-item-9797 post-9797 product type-product status-publish has-post-thumbnail product_cat-oem-odm first instock shipping-taxable product-type-simple\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fdd4789 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fdd4789\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e642aab l-col\" data-id=\"e642aab\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc9639b elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"cc9639b\" data-element_type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"1280\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/1-Photoroom-2.png\" class=\"attachment-full size-full wp-image-3873 lazyload\" alt=\"\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/1-Photoroom-2.png 1280w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/1-Photoroom-2-300x300.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/1-Photoroom-2-100x100.png 100w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/1-Photoroom-2-600x600.png 600w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/1-Photoroom-2-1024x1024.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/1-Photoroom-2-150x150.png 150w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/1-Photoroom-2-768x768.png 768w\" data-sizes=\"(max-width: 1280px) 100vw, 1280px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1280px; --smush-placeholder-aspect-ratio: 1280\/1280;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"1280\" src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/1-Photoroom-2.png\" class=\"attachment-full size-full wp-image-3873\" alt=\"\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/1-Photoroom-2.png 1280w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/1-Photoroom-2-300x300.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/1-Photoroom-2-100x100.png 100w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/1-Photoroom-2-600x600.png 600w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/1-Photoroom-2-1024x1024.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/1-Photoroom-2-150x150.png 150w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/1-Photoroom-2-768x768.png 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e579e85 elementor-widget__width-initial elementor-absolute elementor-widget elementor-widget-text-editor\" data-id=\"e579e85\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tOEM\/ODM\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-99a19aa elementor-section-full_width sec elementor-section-height-default elementor-section-height-default\" data-id=\"99a19aa\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-228aac0\" data-id=\"228aac0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30eb8c4 pt-h3 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"30eb8c4\" data-element_type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">5-Panel Camper Hat<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-63a52e7\" data-id=\"63a52e7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd7eec9 elementor-mobile-align-left elementor-widget elementor-widget-post-info\" data-id=\"bd7eec9\" data-element_type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-inline-items elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-88d16c9 elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-custom\">\n\t\t\t\t\t\t\t\t\t\tJC-CP-05\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b398de8 elementor-section-full_width sec elementor-section-height-default elementor-section-height-default\" data-id=\"b398de8\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6897566\" data-id=\"6897566\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0711a71 new elementor-widget elementor-widget-theme-post-content\" data-id=\"0711a71\" data-element_type=\"widget\" data-widget_type=\"theme-post-content.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"text-sm text-brand-700 font-medium mb-4\">MOQ:\u00a0100 pcs\/design<\/p>\n<div class=\"mb-6\">\n<ul class=\"text-sm text-gray-600 space-y-1\">\n<li class=\"flex items-center\">Nylon\/Cotton<\/li>\n<li class=\"flex items-center\">Clip Closure<\/li>\n<li class=\"flex items-center\">Screen Print Logo<\/li>\n<\/ul>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-161d34e elementor-section-full_width sec elementor-section-height-default elementor-section-height-default\" data-id=\"161d34e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2e296ce\" data-id=\"2e296ce\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c7d5abb elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"c7d5abb\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjEwNjYxIiwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Request Quote<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"9555\" class=\"elementor elementor-9555 e-loop-item e-loop-item-9799 post-9799 product type-product status-publish has-post-thumbnail product_cat-oem-odm  instock shipping-taxable product-type-simple\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fdd4789 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fdd4789\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e642aab l-col\" data-id=\"e642aab\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc9639b elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"cc9639b\" data-element_type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/s-l960-4-1.webp\" class=\"attachment-full size-full wp-image-4145 lazyload\" alt=\"\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/s-l960-4-1.webp 800w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/s-l960-4-1-300x300.webp 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/s-l960-4-1-100x100.webp 100w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/s-l960-4-1-600x600.webp 600w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/s-l960-4-1-150x150.webp 150w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/s-l960-4-1-768x768.webp 768w\" data-sizes=\"(max-width: 800px) 100vw, 800px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 800px; --smush-placeholder-aspect-ratio: 800\/800;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/s-l960-4-1.webp\" class=\"attachment-full size-full wp-image-4145\" alt=\"\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/s-l960-4-1.webp 800w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/s-l960-4-1-300x300.webp 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/s-l960-4-1-100x100.webp 100w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/s-l960-4-1-600x600.webp 600w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/s-l960-4-1-150x150.webp 150w, https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/s-l960-4-1-768x768.webp 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e579e85 elementor-widget__width-initial elementor-absolute elementor-widget elementor-widget-text-editor\" data-id=\"e579e85\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tOEM\/ODM\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-99a19aa elementor-section-full_width sec elementor-section-height-default elementor-section-height-default\" data-id=\"99a19aa\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-228aac0\" data-id=\"228aac0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30eb8c4 pt-h3 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"30eb8c4\" data-element_type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Camo Tactical Cap<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-63a52e7\" data-id=\"63a52e7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd7eec9 elementor-mobile-align-left elementor-widget elementor-widget-post-info\" data-id=\"bd7eec9\" data-element_type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-inline-items elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-88d16c9 elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-custom\">\n\t\t\t\t\t\t\t\t\t\tJC-TC-CAMO\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b398de8 elementor-section-full_width sec elementor-section-height-default elementor-section-height-default\" data-id=\"b398de8\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6897566\" data-id=\"6897566\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0711a71 new elementor-widget elementor-widget-theme-post-content\" data-id=\"0711a71\" data-element_type=\"widget\" data-widget_type=\"theme-post-content.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"text-sm text-brand-700 font-medium mb-4\">MOQ:\u00a0100 pcs\/design<\/p>\n<div class=\"mb-6\">\n<ul class=\"text-sm text-gray-600 space-y-1\">\n<li class=\"flex items-center\">Ripstop Fabric<\/li>\n<li class=\"flex items-center\">Velcro Patch Area<\/li>\n<li class=\"flex items-center\">Adjustable Fit<\/li>\n<\/ul>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-161d34e elementor-section-full_width sec elementor-section-height-default elementor-section-height-default\" data-id=\"161d34e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2e296ce\" data-id=\"2e296ce\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c7d5abb elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"c7d5abb\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjEwNjYxIiwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Request Quote<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-042ac92 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"042ac92\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-97cb9ec\" data-id=\"97cb9ec\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2288caf elementor-widget elementor-widget-text-editor\" data-id=\"2288caf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLooking for a different style? We have 100+ molds available.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20319d1 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"20319d1\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">View Full Catalog<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cb70df9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cb70df9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6ed265e\" data-id=\"6ed265e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c1d568c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c1d568c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-75b1bfb\" data-id=\"75b1bfb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b83cb5 elementor-widget elementor-widget-heading\" data-id=\"1b83cb5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Manufacturing Capability<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18a1a4e elementor-widget elementor-widget-text-editor\" data-id=\"18a1a4e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tWe provide end-to-end customization. Every detail from the fabric choice to the internal\ntaping can be branded to your requirements.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6b5db2d elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6b5db2d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-67c7542\" data-id=\"67c7542\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a4c60f2 feature-image active elementor-widget elementor-widget-image\" data-id=\"a4c60f2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1184\" height=\"880\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_experience_16646dc9.png\" class=\"attachment-full size-full wp-image-11123 lazyload\" alt=\"\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_experience_16646dc9.png 1184w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_experience_16646dc9-300x223.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_experience_16646dc9-1024x761.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_experience_16646dc9-768x571.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_experience_16646dc9-16x12.png 16w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_experience_16646dc9-600x446.png 600w\" data-sizes=\"(max-width: 1184px) 100vw, 1184px\" title=\"workforceexperience16646dc9  JoinTop | Custom Hat Manufacturer  Supplier | OEM  ODM Headwear Factory\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1184px; --smush-placeholder-aspect-ratio: 1184\/880;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1184\" height=\"880\" src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_experience_16646dc9.png\" class=\"attachment-full size-full wp-image-11123\" alt=\"\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_experience_16646dc9.png 1184w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_experience_16646dc9-300x223.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_experience_16646dc9-1024x761.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_experience_16646dc9-768x571.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_experience_16646dc9-16x12.png 16w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_experience_16646dc9-600x446.png 600w\" sizes=\"(max-width: 1184px) 100vw, 1184px\" title=\"workforceexperience16646dc9  JoinTop | Custom Hat Manufacturer  Supplier | OEM  ODM Headwear Factory\" \/><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4bf31b feature-image  elementor-widget elementor-widget-image\" data-id=\"e4bf31b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1184\" height=\"880\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_qc_20b86402.png\" class=\"attachment-full size-full wp-image-11125 lazyload\" alt=\"\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_qc_20b86402.png 1184w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_qc_20b86402-300x223.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_qc_20b86402-1024x761.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_qc_20b86402-768x571.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_qc_20b86402-16x12.png 16w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_qc_20b86402-600x446.png 600w\" data-sizes=\"(max-width: 1184px) 100vw, 1184px\" title=\"workforceqc20b86402  JoinTop | Custom Hat Manufacturer  Supplier | OEM  ODM Headwear Factory\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1184px; --smush-placeholder-aspect-ratio: 1184\/880;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1184\" height=\"880\" src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_qc_20b86402.png\" class=\"attachment-full size-full wp-image-11125\" alt=\"\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_qc_20b86402.png 1184w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_qc_20b86402-300x223.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_qc_20b86402-1024x761.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_qc_20b86402-768x571.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_qc_20b86402-16x12.png 16w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_qc_20b86402-600x446.png 600w\" sizes=\"(max-width: 1184px) 100vw, 1184px\" title=\"workforceqc20b86402  JoinTop | Custom Hat Manufacturer  Supplier | OEM  ODM Headwear Factory\" \/><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8291850 feature-image  elementor-widget elementor-widget-image\" data-id=\"8291850\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1184\" height=\"880\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_embroidery_3c0366f4.png\" class=\"attachment-full size-full wp-image-11126 lazyload\" alt=\"\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_embroidery_3c0366f4.png 1184w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_embroidery_3c0366f4-300x223.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_embroidery_3c0366f4-1024x761.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_embroidery_3c0366f4-768x571.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_embroidery_3c0366f4-16x12.png 16w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_embroidery_3c0366f4-600x446.png 600w\" data-sizes=\"(max-width: 1184px) 100vw, 1184px\" title=\"workforceembroidery3c0366f4  JoinTop | Custom Hat Manufacturer  Supplier | OEM  ODM Headwear Factory\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1184px; --smush-placeholder-aspect-ratio: 1184\/880;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1184\" height=\"880\" src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_embroidery_3c0366f4.png\" class=\"attachment-full size-full wp-image-11126\" alt=\"\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_embroidery_3c0366f4.png 1184w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_embroidery_3c0366f4-300x223.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_embroidery_3c0366f4-1024x761.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_embroidery_3c0366f4-768x571.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_embroidery_3c0366f4-16x12.png 16w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_embroidery_3c0366f4-600x446.png 600w\" sizes=\"(max-width: 1184px) 100vw, 1184px\" title=\"workforceembroidery3c0366f4  JoinTop | Custom Hat Manufacturer  Supplier | OEM  ODM Headwear Factory\" \/><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e72fbb feature-image  elementor-widget elementor-widget-image\" data-id=\"9e72fbb\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1184\" height=\"880\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_team_acdbc6bd.png\" class=\"attachment-full size-full wp-image-11127 lazyload\" alt=\"\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_team_acdbc6bd.png 1184w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_team_acdbc6bd-300x223.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_team_acdbc6bd-1024x761.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_team_acdbc6bd-768x571.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_team_acdbc6bd-16x12.png 16w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_team_acdbc6bd-600x446.png 600w\" data-sizes=\"(max-width: 1184px) 100vw, 1184px\" title=\"workforceteamacdbc6bd  JoinTop | Custom Hat Manufacturer  Supplier | OEM  ODM Headwear Factory\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1184px; --smush-placeholder-aspect-ratio: 1184\/880;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1184\" height=\"880\" src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_team_acdbc6bd.png\" class=\"attachment-full size-full wp-image-11127\" alt=\"\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_team_acdbc6bd.png 1184w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_team_acdbc6bd-300x223.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_team_acdbc6bd-1024x761.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_team_acdbc6bd-768x571.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_team_acdbc6bd-16x12.png 16w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/workforce_team_acdbc6bd-600x446.png 600w\" sizes=\"(max-width: 1184px) 100vw, 1184px\" title=\"workforceteamacdbc6bd  JoinTop | Custom Hat Manufacturer  Supplier | OEM  ODM Headwear Factory\" \/><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d51100 elementor-widget elementor-widget-html\" data-id=\"3d51100\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script>\r\njQuery(document).ready(function ($) {\r\n\r\n    $('.feature-btn').on('click', function (e) {\r\n        e.preventDefault();\r\n\r\n        \/\/ Get index of clicked feature button\r\n        var index = $('.feature-btn').index(this);\r\n\r\n        \/\/ Button active state\r\n        $('.feature-btn').removeClass('active');\r\n        $(this).addClass('active');\r\n\r\n        \/\/ Image switching\r\n        $('.feature-image').removeClass('active').fadeOut(150);\r\n        $('.feature-image').eq(index).fadeIn(150).addClass('active');\r\n    });\r\n\r\n});\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1575646\" data-id=\"1575646\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bad2d9f elementor-widget elementor-widget-heading\" data-id=\"bad2d9f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Experienced Workforce<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd2a43f elementor-widget elementor-widget-text-editor\" data-id=\"fd2a43f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tWith years of hands-on experience in custom cap manufacturing, our skilled team delivers consistent quality, handles complex designs, and ensures reliable production timelines.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9047ef7 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"9047ef7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a3acb04\" data-id=\"a3acb04\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-978caca elementor-align-justify feature-btn active elementor-widget elementor-widget-button\" data-id=\"978caca\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">5\u201310 Years Average Experience<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c5d3656\" data-id=\"c5d3656\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-80d71a6 elementor-align-justify feature-btn elementor-widget elementor-widget-button\" data-id=\"80d71a6\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Dedicated QC Staff<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d9d4616 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"d9d4616\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e8c27dc\" data-id=\"e8c27dc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f6fb098 elementor-align-justify feature-btn elementor-widget elementor-widget-button\" data-id=\"f6fb098\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Skilled Embroidery Operators<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2000a47\" data-id=\"2000a47\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5cb7611 elementor-align-justify feature-btn elementor-widget elementor-widget-button\" data-id=\"5cb7611\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Stable Production Team<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5e79889 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"5e79889\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-93bff6f\" data-id=\"93bff6f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-96bbe63 elementor-widget elementor-widget-heading\" data-id=\"96bbe63\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Logo &amp; Decoration<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f8f7b3f elementor-widget elementor-widget-text-editor\" data-id=\"f8f7b3f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tOur factory utilizes state-of-the-art Tajima embroidery machines and silk screen printing to ensure your logo stands out. We offer various techniques to match your brand identity.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b4ab7db elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"b4ab7db\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-fea25ec\" data-id=\"fea25ec\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c48b57f elementor-align-justify logo-btn active elementor-widget elementor-widget-button\" data-id=\"c48b57f\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">3D Puff Embroidery<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ccce9be\" data-id=\"ccce9be\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a73a4b5 elementor-align-justify logo-btn elementor-widget elementor-widget-button\" data-id=\"a73a4b5\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Flat Embroidery<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2ed8b88 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2ed8b88\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-07b7f51\" data-id=\"07b7f51\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-128c307 elementor-align-justify logo-btn elementor-widget elementor-widget-button\" data-id=\"128c307\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Woven\/Leather Patches<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1c8d1e1\" data-id=\"1c8d1e1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-66312ad elementor-align-justify logo-btn elementor-widget elementor-widget-button\" data-id=\"66312ad\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Heat Transfer &amp; Screen Print<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3cc9823\" data-id=\"3cc9823\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c1143f4 logo-image active elementor-widget elementor-widget-image\" data-id=\"c1143f4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1184\" height=\"880\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/1st.jpg\" class=\"attachment-full size-full wp-image-11166 lazyload\" alt=\"\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/1st.jpg 1184w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/1st-300x223.jpg 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/1st-1024x761.jpg 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/1st-768x571.jpg 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/1st-16x12.jpg 16w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/1st-600x446.jpg 600w\" data-sizes=\"(max-width: 1184px) 100vw, 1184px\" title=\"1st  JoinTop | Custom Hat Manufacturer  Supplier | OEM  ODM Headwear Factory\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1184px; --smush-placeholder-aspect-ratio: 1184\/880;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1184\" height=\"880\" src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/1st.jpg\" class=\"attachment-full size-full wp-image-11166\" alt=\"\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/1st.jpg 1184w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/1st-300x223.jpg 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/1st-1024x761.jpg 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/1st-768x571.jpg 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/1st-16x12.jpg 16w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/1st-600x446.jpg 600w\" sizes=\"(max-width: 1184px) 100vw, 1184px\" title=\"1st  JoinTop | Custom Hat Manufacturer  Supplier | OEM  ODM Headwear Factory\" \/><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e8f8d42 logo-image  elementor-widget elementor-widget-image\" data-id=\"e8f8d42\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1184\" height=\"880\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/logo_flat_embroidery_05fabe94.png\" class=\"attachment-full size-full wp-image-11167 lazyload\" alt=\"\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/logo_flat_embroidery_05fabe94.png 1184w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/logo_flat_embroidery_05fabe94-300x223.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/logo_flat_embroidery_05fabe94-1024x761.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/logo_flat_embroidery_05fabe94-768x571.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/logo_flat_embroidery_05fabe94-16x12.png 16w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/logo_flat_embroidery_05fabe94-600x446.png 600w\" data-sizes=\"(max-width: 1184px) 100vw, 1184px\" title=\"logoflatembroidery05fabe94  JoinTop | Custom Hat Manufacturer  Supplier | OEM  ODM Headwear Factory\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1184px; --smush-placeholder-aspect-ratio: 1184\/880;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1184\" height=\"880\" src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/logo_flat_embroidery_05fabe94.png\" class=\"attachment-full size-full wp-image-11167\" alt=\"\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/logo_flat_embroidery_05fabe94.png 1184w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/logo_flat_embroidery_05fabe94-300x223.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/logo_flat_embroidery_05fabe94-1024x761.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/logo_flat_embroidery_05fabe94-768x571.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/logo_flat_embroidery_05fabe94-16x12.png 16w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/logo_flat_embroidery_05fabe94-600x446.png 600w\" sizes=\"(max-width: 1184px) 100vw, 1184px\" title=\"logoflatembroidery05fabe94  JoinTop | Custom Hat Manufacturer  Supplier | OEM  ODM Headwear Factory\" \/><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ed01e4 logo-image elementor-widget elementor-widget-image\" data-id=\"0ed01e4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1184\" height=\"880\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/logo_patches_d6fadf90.png\" class=\"attachment-full size-full wp-image-11171 lazyload\" alt=\"\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/logo_patches_d6fadf90.png 1184w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/logo_patches_d6fadf90-300x223.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/logo_patches_d6fadf90-1024x761.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/logo_patches_d6fadf90-768x571.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/logo_patches_d6fadf90-16x12.png 16w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/logo_patches_d6fadf90-600x446.png 600w\" data-sizes=\"(max-width: 1184px) 100vw, 1184px\" title=\"logopatchesd6fadf90  JoinTop | Custom Hat Manufacturer  Supplier | OEM  ODM Headwear Factory\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1184px; --smush-placeholder-aspect-ratio: 1184\/880;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1184\" height=\"880\" src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/logo_patches_d6fadf90.png\" class=\"attachment-full size-full wp-image-11171\" alt=\"\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/logo_patches_d6fadf90.png 1184w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/logo_patches_d6fadf90-300x223.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/logo_patches_d6fadf90-1024x761.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/logo_patches_d6fadf90-768x571.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/logo_patches_d6fadf90-16x12.png 16w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/logo_patches_d6fadf90-600x446.png 600w\" sizes=\"(max-width: 1184px) 100vw, 1184px\" title=\"logopatchesd6fadf90  JoinTop | Custom Hat Manufacturer  Supplier | OEM  ODM Headwear Factory\" \/><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f0ae502 logo-image elementor-widget elementor-widget-image\" data-id=\"f0ae502\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1184\" height=\"880\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/logo_heat_transfer_0ae2cf9b.png\" class=\"attachment-full size-full wp-image-11172 lazyload\" alt=\"\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/logo_heat_transfer_0ae2cf9b.png 1184w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/logo_heat_transfer_0ae2cf9b-300x223.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/logo_heat_transfer_0ae2cf9b-1024x761.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/logo_heat_transfer_0ae2cf9b-768x571.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/logo_heat_transfer_0ae2cf9b-16x12.png 16w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/logo_heat_transfer_0ae2cf9b-600x446.png 600w\" data-sizes=\"(max-width: 1184px) 100vw, 1184px\" title=\"logoheattransfer0ae2cf9b  JoinTop | Custom Hat Manufacturer  Supplier | OEM  ODM Headwear Factory\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1184px; --smush-placeholder-aspect-ratio: 1184\/880;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1184\" height=\"880\" src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/logo_heat_transfer_0ae2cf9b.png\" class=\"attachment-full size-full wp-image-11172\" alt=\"\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/logo_heat_transfer_0ae2cf9b.png 1184w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/logo_heat_transfer_0ae2cf9b-300x223.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/logo_heat_transfer_0ae2cf9b-1024x761.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/logo_heat_transfer_0ae2cf9b-768x571.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/logo_heat_transfer_0ae2cf9b-16x12.png 16w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/logo_heat_transfer_0ae2cf9b-600x446.png 600w\" sizes=\"(max-width: 1184px) 100vw, 1184px\" title=\"logoheattransfer0ae2cf9b  JoinTop | Custom Hat Manufacturer  Supplier | OEM  ODM Headwear Factory\" \/><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c9dabc elementor-widget elementor-widget-html\" data-id=\"1c9dabc\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script>\r\njQuery(document).ready(function ($) {\r\n\r\n    $('.logo-btn').on('click', function (e) {\r\n        e.preventDefault();\r\n\r\n        \/\/ Get index of clicked logo button\r\n        var index = $('.logo-btn').index(this);\r\n\r\n        \/\/ Button active state\r\n        $('.logo-btn').removeClass('active');\r\n        $(this).addClass('active');\r\n\r\n        \/\/ Image switching\r\n        $('.logo-image').removeClass('active').fadeOut(150);\r\n        $('.logo-image').eq(index).fadeIn(150).addClass('active');\r\n    });\r\n\r\n});\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-05c38f1 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"05c38f1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-bb4ca2f\" data-id=\"bb4ca2f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8c2f7d7 closures-image active elementor-widget elementor-widget-image\" data-id=\"8c2f7d7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1184\" height=\"880\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_snapback_aa59aecf.png\" class=\"attachment-full size-full wp-image-11209 lazyload\" alt=\"\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_snapback_aa59aecf.png 1184w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_snapback_aa59aecf-300x223.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_snapback_aa59aecf-1024x761.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_snapback_aa59aecf-768x571.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_snapback_aa59aecf-16x12.png 16w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_snapback_aa59aecf-600x446.png 600w\" data-sizes=\"(max-width: 1184px) 100vw, 1184px\" title=\"closuresnapbackaa59aecf  JoinTop | Custom Hat Manufacturer  Supplier | OEM  ODM Headwear Factory\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1184px; --smush-placeholder-aspect-ratio: 1184\/880;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1184\" height=\"880\" src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_snapback_aa59aecf.png\" class=\"attachment-full size-full wp-image-11209\" alt=\"\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_snapback_aa59aecf.png 1184w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_snapback_aa59aecf-300x223.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_snapback_aa59aecf-1024x761.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_snapback_aa59aecf-768x571.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_snapback_aa59aecf-16x12.png 16w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_snapback_aa59aecf-600x446.png 600w\" sizes=\"(max-width: 1184px) 100vw, 1184px\" title=\"closuresnapbackaa59aecf  JoinTop | Custom Hat Manufacturer  Supplier | OEM  ODM Headwear Factory\" \/><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f795918 closures-image elementor-widget elementor-widget-image\" data-id=\"f795918\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1184\" height=\"880\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_buckle_f7a066eb.png\" class=\"attachment-full size-full wp-image-11210 lazyload\" alt=\"\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_buckle_f7a066eb.png 1184w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_buckle_f7a066eb-300x223.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_buckle_f7a066eb-1024x761.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_buckle_f7a066eb-768x571.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_buckle_f7a066eb-16x12.png 16w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_buckle_f7a066eb-600x446.png 600w\" data-sizes=\"(max-width: 1184px) 100vw, 1184px\" title=\"closurebucklef7a066eb  JoinTop | Custom Hat Manufacturer  Supplier | OEM  ODM Headwear Factory\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1184px; --smush-placeholder-aspect-ratio: 1184\/880;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1184\" height=\"880\" src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_buckle_f7a066eb.png\" class=\"attachment-full size-full wp-image-11210\" alt=\"\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_buckle_f7a066eb.png 1184w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_buckle_f7a066eb-300x223.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_buckle_f7a066eb-1024x761.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_buckle_f7a066eb-768x571.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_buckle_f7a066eb-16x12.png 16w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_buckle_f7a066eb-600x446.png 600w\" sizes=\"(max-width: 1184px) 100vw, 1184px\" title=\"closurebucklef7a066eb  JoinTop | Custom Hat Manufacturer  Supplier | OEM  ODM Headwear Factory\" \/><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55eb285 closures-image elementor-widget elementor-widget-image\" data-id=\"55eb285\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1184\" height=\"880\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_taping_08769222.png\" class=\"attachment-full size-full wp-image-11211 lazyload\" alt=\"\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_taping_08769222.png 1184w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_taping_08769222-300x223.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_taping_08769222-1024x761.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_taping_08769222-768x571.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_taping_08769222-16x12.png 16w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_taping_08769222-600x446.png 600w\" data-sizes=\"(max-width: 1184px) 100vw, 1184px\" title=\"closuretaping08769222  JoinTop | Custom Hat Manufacturer  Supplier | OEM  ODM Headwear Factory\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1184px; --smush-placeholder-aspect-ratio: 1184\/880;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1184\" height=\"880\" src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_taping_08769222.png\" class=\"attachment-full size-full wp-image-11211\" alt=\"\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_taping_08769222.png 1184w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_taping_08769222-300x223.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_taping_08769222-1024x761.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_taping_08769222-768x571.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_taping_08769222-16x12.png 16w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_taping_08769222-600x446.png 600w\" sizes=\"(max-width: 1184px) 100vw, 1184px\" title=\"closuretaping08769222  JoinTop | Custom Hat Manufacturer  Supplier | OEM  ODM Headwear Factory\" \/><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc2f1cf closures-image elementor-widget elementor-widget-image\" data-id=\"dc2f1cf\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1184\" height=\"880\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_labeling_bd61d68c.png\" class=\"attachment-full size-full wp-image-11212 lazyload\" alt=\"\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_labeling_bd61d68c.png 1184w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_labeling_bd61d68c-300x223.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_labeling_bd61d68c-1024x761.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_labeling_bd61d68c-768x571.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_labeling_bd61d68c-16x12.png 16w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_labeling_bd61d68c-600x446.png 600w\" data-sizes=\"(max-width: 1184px) 100vw, 1184px\" title=\"closurelabelingbd61d68c  JoinTop | Custom Hat Manufacturer  Supplier | OEM  ODM Headwear Factory\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1184px; --smush-placeholder-aspect-ratio: 1184\/880;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1184\" height=\"880\" src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_labeling_bd61d68c.png\" class=\"attachment-full size-full wp-image-11212\" alt=\"\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_labeling_bd61d68c.png 1184w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_labeling_bd61d68c-300x223.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_labeling_bd61d68c-1024x761.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_labeling_bd61d68c-768x571.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_labeling_bd61d68c-16x12.png 16w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/closure_labeling_bd61d68c-600x446.png 600w\" sizes=\"(max-width: 1184px) 100vw, 1184px\" title=\"closurelabelingbd61d68c  JoinTop | Custom Hat Manufacturer  Supplier | OEM  ODM Headwear Factory\" \/><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7cce83e elementor-widget elementor-widget-html\" data-id=\"7cce83e\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script>\r\njQuery(document).ready(function ($) {\r\n\r\n    $('.closures-btn').on('click', function (e) {\r\n        e.preventDefault();\r\n\r\n        \/\/ Get index of clicked closures-btn\r\n        var index = $('.closures-btn').index(this);\r\n\r\n        \/\/ Button active state\r\n        $('.closures-btn').removeClass('active');\r\n        $(this).addClass('active');\r\n\r\n        \/\/ Image switching\r\n        $('.closures-image').removeClass('active').fadeOut(150);\r\n        $('.closures-image').eq(index).fadeIn(150).addClass('active');\r\n    });\r\n\r\n});\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-72ea122\" data-id=\"72ea122\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac1be9b elementor-widget elementor-widget-heading\" data-id=\"ac1be9b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Closures &amp; Accessories <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f7e7b8 elementor-widget elementor-widget-text-editor\" data-id=\"1f7e7b8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tThe finishing touches matter. Select the perfect back closure and add custom interior taping, woven labels, or hang tags for a retail-ready product.\n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e632c4a elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"e632c4a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9649d6d\" data-id=\"9649d6d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9ef811d elementor-align-justify closures-btn active elementor-widget elementor-widget-button\" data-id=\"9ef811d\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Snapback &amp; Velcro<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4dcd708\" data-id=\"4dcd708\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-561d190 elementor-align-justify closures-btn elementor-widget elementor-widget-button\" data-id=\"561d190\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Metal Buckle &amp; Grommet<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0705ba3 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"0705ba3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2a2f9cf\" data-id=\"2a2f9cf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46ff1ed elementor-align-justify closures-btn elementor-widget elementor-widget-button\" data-id=\"46ff1ed\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Custom Inner Taping<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4e7f784\" data-id=\"4e7f784\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a565f0 elementor-align-justify closures-btn elementor-widget elementor-widget-button\" data-id=\"8a565f0\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Private Labeling<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-df04cab elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"df04cab\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-441b448\" data-id=\"441b448\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f310fcd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f310fcd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-87f8b46\" data-id=\"87f8b46\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b82cf59 elementor-widget elementor-widget-heading\" data-id=\"b82cf59\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Endless Possibilities<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-281eda0 elementor-widget elementor-widget-heading\" data-id=\"281eda0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Fully Customizable product<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e09df6 elementor-widget elementor-widget-text-editor\" data-id=\"8e09df6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Every element of your headwar can be tailord. Explore our customization<br \/>options below<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-00ac09e elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"00ac09e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-f6eb740 grid-how\" data-id=\"f6eb740\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8163665 custom-tab elementor-widget elementor-widget-eael-adv-tabs\" data-id=\"8163665\" data-element_type=\"widget\" data-widget_type=\"eael-adv-tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div data-scroll-on-click=\"no\" data-scroll-speed=\"300\" id=\"eael-advance-tabs-8163665\" class=\"eael-advance-tabs eael-tabs-horizontal eael-tab-auto-active\" data-tabid=\"8163665\">\n            <div class=\"eael-tabs-nav\">\n                <ul class=\"\" role=\"tablist\">\n                                            <li id=\"material\" class=\"inactive eael-tab-item-trigger eael-tab-nav-item\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"material-tab\" aria-expanded=\"false\">\n                            \n                            \n                            \n                                                            <span class=\"eael-tab-title title-after-icon\" >Material<\/span>                                                    <\/li>\n                                            <li id=\"colors\" class=\"inactive eael-tab-item-trigger eael-tab-nav-item\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"colors-tab\" aria-expanded=\"false\">\n                            \n                            \n                            \n                                                            <span class=\"eael-tab-title title-after-icon\" >Colors<\/span>                                                    <\/li>\n                                            <li id=\"style\" class=\"inactive eael-tab-item-trigger eael-tab-nav-item\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"style-tab\" aria-expanded=\"false\">\n                            \n                            \n                            \n                                                            <span class=\"eael-tab-title title-after-icon\" >Stil<\/span>                                                    <\/li>\n                                            <li id=\"packaging-delivery\" class=\"inactive eael-tab-item-trigger eael-tab-nav-item\" aria-selected=\"false\" data-tab=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"packaging-delivery-tab\" aria-expanded=\"false\">\n                            \n                            \n                            \n                                                            <span class=\"eael-tab-title title-after-icon\" >Packaging &#038; Delivery<\/span>                                                    <\/li>\n                    \n                                  <\/ul>\n            <\/div>\n            \n            <div class=\"eael-tabs-content\">\n\t\t        \n                    <div id=\"material-tab\" class=\"clearfix eael-tab-content-item inactive\" data-title-link=\"material-tab\">\n\t\t\t\t        <style>.elementor-10388 .elementor-element.elementor-element-1c09abf:not(.elementor-motion-effects-element-type-background), .elementor-10388 .elementor-element.elementor-element-1c09abf > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:#FFFFFF;}.elementor-10388 .elementor-element.elementor-element-1c09abf > .elementor-container{max-width:1120px;}.elementor-10388 .elementor-element.elementor-element-1c09abf, .elementor-10388 .elementor-element.elementor-element-1c09abf > .elementor-background-overlay{border-radius:10px 10px 10px 10px;}.elementor-10388 .elementor-element.elementor-element-1c09abf{transition:background 0.3s, border 0.3s, border-radius 0.3s, box-shadow 0.3s;margin-top:0px;margin-bottom:0px;padding:40px 0px 40px 40px;}.elementor-10388 .elementor-element.elementor-element-1c09abf > .elementor-background-overlay{transition:background 0.3s, border-radius 0.3s, opacity 0.3s;}.elementor-10388 .elementor-element.elementor-element-95b7414 > .elementor-element-populated{padding:0px 0px 0px 0px;}.elementor-10388 .elementor-element.elementor-element-2244027 .e-gallery-item:hover .elementor-gallery-item__overlay, .elementor-10388 .elementor-element.elementor-element-2244027 .e-gallery-item:focus .elementor-gallery-item__overlay{background-color:rgba(0,0,0,0.5);}.elementor-10388 .elementor-element.elementor-element-2244027 > .elementor-widget-container{margin:0px 0px 0px 0px;padding:0px 0px 0px 0px;}.elementor-10388 .elementor-element.elementor-element-2244027{--image-border-radius:8px;--image-transition-duration:800ms;--overlay-transition-duration:800ms;--content-text-align:center;--content-padding:20px;--content-transition-duration:800ms;--content-transition-delay:800ms;}@media(max-width:1366px){.elementor-10388 .elementor-element.elementor-element-1c09abf, .elementor-10388 .elementor-element.elementor-element-1c09abf > .elementor-background-overlay{border-radius:10px 10px 10px 10px;}.elementor-10388 .elementor-element.elementor-element-1c09abf{padding:40px 40px 40px 40px;}}@media(max-width:1024px){.elementor-10388 .elementor-element.elementor-element-1c09abf{padding:25px 0px 25px 0px;}}@media(max-width:767px){.elementor-10388 .elementor-element.elementor-element-1c09abf{padding:15px 0px 15px 0px;}.elementor-10388 .elementor-element.elementor-element-95b7414 > .elementor-widget-wrap > .elementor-widget:not(.elementor-widget__width-auto):not(.elementor-widget__width-initial):not(:last-child):not(.elementor-absolute){margin-bottom:0px;}.elementor-10388 .elementor-element.elementor-element-95b7414 > .elementor-element-populated{margin:0px 0px 0px 0px;--e-column-margin-right:0px;--e-column-margin-left:0px;padding:0px 0px 0px 0px;}}<\/style>\t\t<div data-elementor-type=\"section\" data-elementor-id=\"10388\" class=\"elementor elementor-10388\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1c09abf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1c09abf\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-95b7414\" data-id=\"95b7414\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2244027 elementor-widget elementor-widget-gallery\" data-id=\"2244027\" data-element_type=\"widget\" data-settings=\"{&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:25,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;aspect_ratio&quot;:&quot;4:3&quot;,&quot;overlay_title&quot;:&quot;title&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;gallery_layout&quot;:&quot;grid&quot;,&quot;columns&quot;:4,&quot;columns_tablet&quot;:2,&quot;columns_mobile&quot;:1,&quot;gap_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;link_to&quot;:&quot;file&quot;,&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/100-Cotton-Twill-.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2244027\" data-elementor-lightbox-title=\"100 Cotton Twill\" data-elementor-lightbox-description=\"#image_title\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTEzNjAsInVybCI6Imh0dHBzOlwvXC9qb2ludG9wY2FwLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNlwvMDFcLzEwMC1Db3R0b24tVHdpbGwtLnBuZyIsInNsaWRlc2hvdyI6IjIyNDQwMjcifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/100-Cotton-Twill-.png\" data-width=\"1184\" data-height=\"880\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t100 Cotton Twill\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Canvas-.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2244027\" data-elementor-lightbox-title=\"Canvas\" data-elementor-lightbox-description=\"#image_title\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTEzNjEsInVybCI6Imh0dHBzOlwvXC9qb2ludG9wY2FwLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNlwvMDFcL0NhbnZhcy0ucG5nIiwic2xpZGVzaG93IjoiMjI0NDAyNyJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Canvas-.png\" data-width=\"1184\" data-height=\"880\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tCanvas\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Corduroy-.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2244027\" data-elementor-lightbox-title=\"Corduroy\" data-elementor-lightbox-description=\"#image_title\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTEzNjIsInVybCI6Imh0dHBzOlwvXC9qb2ludG9wY2FwLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNlwvMDFcL0NvcmR1cm95LS5wbmciLCJzbGlkZXNob3ciOiIyMjQ0MDI3In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Corduroy-.png\" data-width=\"1184\" data-height=\"880\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tCorduroy\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Cotton-Polyester-Blend-.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2244027\" data-elementor-lightbox-title=\"Cotton-Polyester Blend\" data-elementor-lightbox-description=\"#image_title\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTEzNjMsInVybCI6Imh0dHBzOlwvXC9qb2ludG9wY2FwLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNlwvMDFcL0NvdHRvbi1Qb2x5ZXN0ZXItQmxlbmQtLnBuZyIsInNsaWRlc2hvdyI6IjIyNDQwMjcifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Cotton-Polyester-Blend-.png\" data-width=\"1184\" data-height=\"880\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tCotton-Polyester Blend\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Denim-.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2244027\" data-elementor-lightbox-title=\"Denim\" data-elementor-lightbox-description=\"#image_title\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTEzNjQsInVybCI6Imh0dHBzOlwvXC9qb2ludG9wY2FwLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNlwvMDFcL0RlbmltLS5wbmciLCJzbGlkZXNob3ciOiIyMjQ0MDI3In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Denim-.png\" data-width=\"1184\" data-height=\"880\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tDenim\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Nylon-.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2244027\" data-elementor-lightbox-title=\"Nylon\" data-elementor-lightbox-description=\"#image_title\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTEzNjUsInVybCI6Imh0dHBzOlwvXC9qb2ludG9wY2FwLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNlwvMDFcL055bG9uLS5wbmciLCJzbGlkZXNob3ciOiIyMjQ0MDI3In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Nylon-.png\" data-width=\"1184\" data-height=\"880\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tNylon\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Polyester-Mesh-.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2244027\" data-elementor-lightbox-title=\"Polyester Mesh\" data-elementor-lightbox-description=\"#image_title\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTEzNjcsInVybCI6Imh0dHBzOlwvXC9qb2ludG9wY2FwLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNlwvMDFcL1BvbHllc3Rlci1NZXNoLS5wbmciLCJzbGlkZXNob3ciOiIyMjQ0MDI3In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Polyester-Mesh-.png\" data-width=\"1184\" data-height=\"880\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tPolyester Mesh\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Polyester-Twill-.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2244027\" data-elementor-lightbox-title=\"Polyester Twill\" data-elementor-lightbox-description=\"#image_title\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTEzNjgsInVybCI6Imh0dHBzOlwvXC9qb2ludG9wY2FwLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNlwvMDFcL1BvbHllc3Rlci1Ud2lsbC0ucG5nIiwic2xpZGVzaG93IjoiMjI0NDAyNyJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Polyester-Twill-.png\" data-width=\"1184\" data-height=\"880\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tPolyester Twill\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Recycled-Polyester-rPET.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2244027\" data-elementor-lightbox-title=\"Recycled Polyester rPET\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTEzNjksInVybCI6Imh0dHBzOlwvXC9qb2ludG9wY2FwLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNlwvMDFcL1JlY3ljbGVkLVBvbHllc3Rlci1yUEVULnBuZyIsInNsaWRlc2hvdyI6IjIyNDQwMjcifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Recycled-Polyester-rPET.png\" data-width=\"1184\" data-height=\"880\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tRecycled Polyester rPET\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Suede-Faux-Suede-.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2244027\" data-elementor-lightbox-title=\"Suede Faux Suede\" data-elementor-lightbox-description=\"#image_title\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTEzNzAsInVybCI6Imh0dHBzOlwvXC9qb2ludG9wY2FwLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNlwvMDFcL1N1ZWRlLUZhdXgtU3VlZGUtLnBuZyIsInNsaWRlc2hvdyI6IjIyNDQwMjcifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Suede-Faux-Suede-.png\" data-width=\"1184\" data-height=\"880\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tSuede Faux Suede\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Washed-Cotton-.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2244027\" data-elementor-lightbox-title=\"Washed Cotton\" data-elementor-lightbox-description=\"#image_title\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTEzNzEsInVybCI6Imh0dHBzOlwvXC9qb2ludG9wY2FwLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNlwvMDFcL1dhc2hlZC1Db3R0b24tLnBuZyIsInNsaWRlc2hvdyI6IjIyNDQwMjcifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Washed-Cotton-.png\" data-width=\"1184\" data-height=\"880\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tWashed Cotton\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t                    <\/div>\n\t\t        \n                    <div id=\"colors-tab\" class=\"clearfix eael-tab-content-item inactive\" data-title-link=\"colors-tab\">\n\t\t\t\t        <style>.elementor-10574 .elementor-element.elementor-element-1c09abf:not(.elementor-motion-effects-element-type-background), .elementor-10574 .elementor-element.elementor-element-1c09abf > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:#FFFFFF;}.elementor-10574 .elementor-element.elementor-element-1c09abf > .elementor-container{max-width:1120px;}.elementor-10574 .elementor-element.elementor-element-1c09abf, .elementor-10574 .elementor-element.elementor-element-1c09abf > .elementor-background-overlay{border-radius:10px 10px 10px 10px;}.elementor-10574 .elementor-element.elementor-element-1c09abf{transition:background 0.3s, border 0.3s, border-radius 0.3s, box-shadow 0.3s;margin-top:0px;margin-bottom:0px;padding:40px 40px 40px 40px;}.elementor-10574 .elementor-element.elementor-element-1c09abf > .elementor-background-overlay{transition:background 0.3s, border-radius 0.3s, opacity 0.3s;}.elementor-10574 .elementor-element.elementor-element-95b7414 > .elementor-element-populated{padding:0px 0px 0px 0px;}.elementor-10574 .elementor-element.elementor-element-c955439{padding:0px 0px 0px 0px;}.elementor-10574 .elementor-element.elementor-element-40b91af > .elementor-widget-wrap > .elementor-widget:not(.elementor-widget__width-auto):not(.elementor-widget__width-initial):not(:last-child):not(.elementor-absolute){margin-bottom:10px;}.elementor-10574 .elementor-element.elementor-element-40b91af > .elementor-element-populated{padding:0px 0px 0px 0px;}.elementor-10574 .elementor-element.elementor-element-29a6bac{text-align:left;}.elementor-10574 .elementor-element.elementor-element-29a6bac .elementor-heading-title{font-family:\"Roboto Flex\", Sans-serif;font-size:26px;font-weight:600;}.elementor-10574 .elementor-element.elementor-element-f122f39{text-align:left;font-family:\"Roboto Flex\", Sans-serif;font-size:18px;font-weight:400;text-transform:none;font-style:normal;line-height:26px;color:#616161;}.elementor-10574 .elementor-element.elementor-element-a0689a4{margin-top:40px;margin-bottom:0px;padding:0px 0px 0px 0px;}.elementor-10574 .elementor-element.elementor-element-d464f45 > .elementor-element-populated{padding:0px 0px 0px 0px;}.elementor-10574 .elementor-element.elementor-element-c63456c .uael-img-gallery-wrap .uael-grid-item{padding-right:calc( 20px\/2 );padding-left:calc( 20px\/2 );align-items:flex-start;display:inline-grid;}.elementor-10574 .elementor-element.elementor-element-c63456c .uael-img-gallery-wrap{margin-left:calc( -20px\/2 );margin-right:calc( -20px\/2 );}.elementor-10574 .elementor-element.elementor-element-c63456c .uael-img-gallery-wrap .uael-grid-item-content{margin-bottom:20px;}.elementor-10574 .elementor-element.elementor-element-c63456c .uael-grid-img-caption{padding:0px 5px 5px 5px;}.elementor-10574 .elementor-element.elementor-element-c63456c .uael-grid-img-thumbnail img{transform:scale(1);opacity:1;}.elementor-10574 .elementor-element.elementor-element-c63456c .uael-grid-gallery-img:hover .uael-grid-img-thumbnail img{opacity:1;}.elementor-10574 .elementor-element.elementor-element-c63456c .uael-img-gallery-wrap .uael-grid-img-caption{text-align:center;}.elementor-10574 .elementor-element.elementor-element-c63456c .uael-grid-img-caption .uael-grid-caption-text{font-size:16px;font-weight:500;text-transform:capitalize;font-style:normal;}@media(max-width:1366px){.elementor-10574 .elementor-element.elementor-element-1c09abf, .elementor-10574 .elementor-element.elementor-element-1c09abf > .elementor-background-overlay{border-radius:10px 10px 10px 10px;}.elementor-10574 .elementor-element.elementor-element-1c09abf{padding:40px 40px 40px 40px;}}@media(max-width:1024px){.elementor-10574 .elementor-element.elementor-element-1c09abf{padding:25px 25px 25px 25px;}}@media(max-width:767px){.elementor-10574 .elementor-element.elementor-element-1c09abf{padding:15px 0px 15px 0px;}.elementor-10574 .elementor-element.elementor-element-95b7414 > .elementor-element-populated{margin:0px 0px 0px 0px;--e-column-margin-right:0px;--e-column-margin-left:0px;padding:0px 0px 0px 0px;}.elementor-10574 .elementor-element.elementor-element-40b91af > .elementor-element-populated{padding:0px 0px 0px 0px;}.elementor-10574 .elementor-element.elementor-element-29a6bac .elementor-heading-title{font-size:26px;line-height:28px;}.elementor-10574 .elementor-element.elementor-element-f122f39{font-size:16px;line-height:24px;}.elementor-10574 .elementor-element.elementor-element-a0689a4{margin-top:0px;margin-bottom:0px;padding:0px 0px 0px 0px;}.elementor-10574 .elementor-element.elementor-element-d464f45{width:100%;}.elementor-10574 .elementor-element.elementor-element-d464f45 > .elementor-widget-wrap > .elementor-widget:not(.elementor-widget__width-auto):not(.elementor-widget__width-initial):not(:last-child):not(.elementor-absolute){margin-bottom:0px;}.elementor-10574 .elementor-element.elementor-element-d464f45 > .elementor-element-populated{margin:0px 0px 0px 0px;--e-column-margin-right:0px;--e-column-margin-left:0px;padding:0px 0px 0px 0px;}.elementor-10574 .elementor-element.elementor-element-c63456c .uael-img-gallery-wrap .uael-grid-item{padding-right:calc( 0px\/2 );padding-left:calc( 0px\/2 );}.elementor-10574 .elementor-element.elementor-element-c63456c .uael-img-gallery-wrap{margin-left:calc( -0px\/2 );margin-right:calc( -0px\/2 );}.elementor-10574 .elementor-element.elementor-element-c63456c .uael-img-gallery-wrap .uael-grid-item-content{margin-bottom:20px;}.elementor-10574 .elementor-element.elementor-element-c63456c > .elementor-widget-container{padding:0px 0px 0px 0px;}}\/* Start custom CSS for uael-image-gallery, class: .elementor-element-c63456c *\/.cus-gallery .uael-grid-img-caption {\r\n    border-radius: 0px 0px 15px 15px;\r\n}\r\n\r\n.cus-gallery .uael-grid-img-thumbnail.uael-ins-target {\r\n    border-radius: 0px 0px 15px 15px !important;\r\n}\/* End custom CSS *\/<\/style>\t\t<div data-elementor-type=\"section\" data-elementor-id=\"10574\" class=\"elementor elementor-10574\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1c09abf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1c09abf\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-95b7414\" data-id=\"95b7414\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c955439 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"c955439\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-40b91af\" data-id=\"40b91af\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29a6bac elementor-widget elementor-widget-heading\" data-id=\"29a6bac\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Colors<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f122f39 elementor-widget elementor-widget-text-editor\" data-id=\"f122f39\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tPick any color or match your exact Pantone shade.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a0689a4 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"a0689a4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-d464f45\" data-id=\"d464f45\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c63456c uael-img-grid__column-6 uael-img-grid-mobile__column-1 cus-gallery uael-img-grid-tablet__column-3 uael-ins-normal uael-img-caption-valign-bottom elementor-widget elementor-widget-uael-image-gallery\" data-id=\"c63456c\" data-element_type=\"widget\" data-settings=\"{&quot;gallery_columns&quot;:&quot;6&quot;,&quot;gallery_columns_mobile&quot;:&quot;1&quot;,&quot;row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;caption_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;0&quot;,&quot;right&quot;:&quot;5&quot;,&quot;bottom&quot;:&quot;5&quot;,&quot;left&quot;:&quot;5&quot;,&quot;isLinked&quot;:false},&quot;column_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;gallery_columns_tablet&quot;:&quot;3&quot;,&quot;column_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;column_gap_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;column_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;row_gap_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;images_valign&quot;:&quot;flex-start&quot;,&quot;caption_padding_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;caption_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;caption_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true}}\" data-widget_type=\"uael-image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"uael-gallery-parent uael-caption-on-image uael-gallery-unjustified\"><div class=\"uael-img-gallery-wrap uael-img-grid-wrap uael-img-grid-masonry-wrap\" data-filter-default=\"All\"><div class=\"uael-grid-item  uael-img-gallery-item-1\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Amber-.png\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Amber--300x300.png\" class=\"attachment-medium size-medium wp-image-11394 lazyload\" alt=\"Amber\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Amber--300x300.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Amber--150x150.png 150w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Amber--768x768.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Amber--12x12.png 12w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Amber--600x600.png 600w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Amber--100x100.png 100w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Amber-.png 1024w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Amber--300x300.png\" class=\"attachment-medium size-medium wp-image-11394\" alt=\"Amber\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Amber--300x300.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Amber--150x150.png 150w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Amber--768x768.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Amber--12x12.png 12w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Amber--600x600.png 600w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Amber--100x100.png 100w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Amber-.png 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/noscript><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><figcaption class=\"uael-grid-img-content\"><div class=\"uael-grid-img-caption\"><h4 class=\"uael-grid-caption-text\">Amber<\/h4><\/div><\/figcaption><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-2\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Black-.png\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Black--300x300.png\" class=\"attachment-medium size-medium wp-image-11395 lazyload\" alt=\"Black\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Black--300x300.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Black--150x150.png 150w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Black--768x768.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Black--12x12.png 12w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Black--600x600.png 600w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Black--100x100.png 100w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Black-.png 1024w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Black--300x300.png\" class=\"attachment-medium size-medium wp-image-11395\" alt=\"Black\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Black--300x300.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Black--150x150.png 150w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Black--768x768.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Black--12x12.png 12w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Black--600x600.png 600w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Black--100x100.png 100w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Black-.png 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/noscript><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><figcaption class=\"uael-grid-img-content\"><div class=\"uael-grid-img-caption\"><h4 class=\"uael-grid-caption-text\">Black<\/h4><\/div><\/figcaption><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-3\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Blue-.png\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Blue--300x300.png\" class=\"attachment-medium size-medium wp-image-11396 lazyload\" alt=\"Blue\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Blue--300x300.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Blue--150x150.png 150w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Blue--768x768.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Blue--12x12.png 12w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Blue--600x600.png 600w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Blue--100x100.png 100w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Blue-.png 1024w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Blue--300x300.png\" class=\"attachment-medium size-medium wp-image-11396\" alt=\"Blue\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Blue--300x300.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Blue--150x150.png 150w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Blue--768x768.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Blue--12x12.png 12w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Blue--600x600.png 600w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Blue--100x100.png 100w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Blue-.png 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/noscript><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><figcaption class=\"uael-grid-img-content\"><div class=\"uael-grid-img-caption\"><h4 class=\"uael-grid-caption-text\">Blue<\/h4><\/div><\/figcaption><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-4\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Charcoal-.png\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Charcoal--300x300.png\" class=\"attachment-medium size-medium wp-image-11397 lazyload\" alt=\"Charcoal\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Charcoal--300x300.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Charcoal--150x150.png 150w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Charcoal--768x768.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Charcoal--12x12.png 12w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Charcoal--600x600.png 600w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Charcoal--100x100.png 100w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Charcoal-.png 1024w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Charcoal--300x300.png\" class=\"attachment-medium size-medium wp-image-11397\" alt=\"Charcoal\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Charcoal--300x300.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Charcoal--150x150.png 150w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Charcoal--768x768.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Charcoal--12x12.png 12w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Charcoal--600x600.png 600w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Charcoal--100x100.png 100w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Charcoal-.png 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/noscript><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><figcaption class=\"uael-grid-img-content\"><div class=\"uael-grid-img-caption\"><h4 class=\"uael-grid-caption-text\">Charcoal<\/h4><\/div><\/figcaption><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-5\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Green-.png\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Green--300x300.png\" class=\"attachment-medium size-medium wp-image-11398 lazyload\" alt=\"Green\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Green--300x300.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Green--150x150.png 150w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Green--768x768.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Green--12x12.png 12w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Green--600x600.png 600w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Green--100x100.png 100w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Green-.png 1024w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Green--300x300.png\" class=\"attachment-medium size-medium wp-image-11398\" alt=\"Green\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Green--300x300.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Green--150x150.png 150w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Green--768x768.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Green--12x12.png 12w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Green--600x600.png 600w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Green--100x100.png 100w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Green-.png 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/noscript><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><figcaption class=\"uael-grid-img-content\"><div class=\"uael-grid-img-caption\"><h4 class=\"uael-grid-caption-text\">Green<\/h4><\/div><\/figcaption><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-6\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Grey-.png\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Grey--300x300.png\" class=\"attachment-medium size-medium wp-image-11399 lazyload\" alt=\"Grey\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Grey--300x300.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Grey--150x150.png 150w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Grey--768x768.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Grey--12x12.png 12w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Grey--600x600.png 600w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Grey--100x100.png 100w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Grey-.png 1024w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Grey--300x300.png\" class=\"attachment-medium size-medium wp-image-11399\" alt=\"Grey\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Grey--300x300.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Grey--150x150.png 150w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Grey--768x768.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Grey--12x12.png 12w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Grey--600x600.png 600w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Grey--100x100.png 100w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Grey-.png 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/noscript><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><figcaption class=\"uael-grid-img-content\"><div class=\"uael-grid-img-caption\"><h4 class=\"uael-grid-caption-text\">Grey<\/h4><\/div><\/figcaption><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-7\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Indigo-.png\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Indigo--300x300.png\" class=\"attachment-medium size-medium wp-image-11400 lazyload\" alt=\"Indigo\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Indigo--300x300.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Indigo--150x150.png 150w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Indigo--768x768.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Indigo--12x12.png 12w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Indigo--600x600.png 600w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Indigo--100x100.png 100w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Indigo-.png 1024w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Indigo--300x300.png\" class=\"attachment-medium size-medium wp-image-11400\" alt=\"Indigo\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Indigo--300x300.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Indigo--150x150.png 150w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Indigo--768x768.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Indigo--12x12.png 12w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Indigo--600x600.png 600w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Indigo--100x100.png 100w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Indigo-.png 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/noscript><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><figcaption class=\"uael-grid-img-content\"><div class=\"uael-grid-img-caption\"><h4 class=\"uael-grid-caption-text\">Indigo<\/h4><\/div><\/figcaption><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-8\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Light-Grey-.png\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Light-Grey--300x300.png\" class=\"attachment-medium size-medium wp-image-11401 lazyload\" alt=\"Light Grey\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Light-Grey--300x300.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Light-Grey--150x150.png 150w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Light-Grey--768x768.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Light-Grey--12x12.png 12w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Light-Grey--600x600.png 600w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Light-Grey--100x100.png 100w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Light-Grey-.png 1024w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Light-Grey--300x300.png\" class=\"attachment-medium size-medium wp-image-11401\" alt=\"Light Grey\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Light-Grey--300x300.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Light-Grey--150x150.png 150w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Light-Grey--768x768.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Light-Grey--12x12.png 12w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Light-Grey--600x600.png 600w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Light-Grey--100x100.png 100w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Light-Grey-.png 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/noscript><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><figcaption class=\"uael-grid-img-content\"><div class=\"uael-grid-img-caption\"><h4 class=\"uael-grid-caption-text\">Light Grey<\/h4><\/div><\/figcaption><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-9\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Orange-.png\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Orange--300x300.png\" class=\"attachment-medium size-medium wp-image-11402 lazyload\" alt=\"Orange\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Orange--300x300.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Orange--150x150.png 150w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Orange--768x768.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Orange--12x12.png 12w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Orange--600x600.png 600w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Orange--100x100.png 100w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Orange-.png 1024w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Orange--300x300.png\" class=\"attachment-medium size-medium wp-image-11402\" alt=\"Orange\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Orange--300x300.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Orange--150x150.png 150w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Orange--768x768.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Orange--12x12.png 12w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Orange--600x600.png 600w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Orange--100x100.png 100w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Orange-.png 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/noscript><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><figcaption class=\"uael-grid-img-content\"><div class=\"uael-grid-img-caption\"><h4 class=\"uael-grid-caption-text\">Orange<\/h4><\/div><\/figcaption><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-10\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Pink-.png\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Pink--300x300.png\" class=\"attachment-medium size-medium wp-image-11403 lazyload\" alt=\"Pink\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Pink--300x300.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Pink--150x150.png 150w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Pink--768x768.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Pink--12x12.png 12w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Pink--600x600.png 600w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Pink--100x100.png 100w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Pink-.png 1024w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Pink--300x300.png\" class=\"attachment-medium size-medium wp-image-11403\" alt=\"Pink\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Pink--300x300.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Pink--150x150.png 150w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Pink--768x768.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Pink--12x12.png 12w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Pink--600x600.png 600w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Pink--100x100.png 100w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Pink-.png 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/noscript><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><figcaption class=\"uael-grid-img-content\"><div class=\"uael-grid-img-caption\"><h4 class=\"uael-grid-caption-text\">Pink<\/h4><\/div><\/figcaption><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-11\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Purple-.png\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Purple--300x300.png\" class=\"attachment-medium size-medium wp-image-11404 lazyload\" alt=\"Purple\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Purple--300x300.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Purple--150x150.png 150w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Purple--768x768.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Purple--12x12.png 12w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Purple--600x600.png 600w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Purple--100x100.png 100w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Purple-.png 1024w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Purple--300x300.png\" class=\"attachment-medium size-medium wp-image-11404\" alt=\"Purple\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Purple--300x300.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Purple--150x150.png 150w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Purple--768x768.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Purple--12x12.png 12w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Purple--600x600.png 600w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Purple--100x100.png 100w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Purple-.png 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/noscript><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><figcaption class=\"uael-grid-img-content\"><div class=\"uael-grid-img-caption\"><h4 class=\"uael-grid-caption-text\">Purple<\/h4><\/div><\/figcaption><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-12\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Red-.png\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Red--300x300.png\" class=\"attachment-medium size-medium wp-image-11405 lazyload\" alt=\"Red\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Red--300x300.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Red--150x150.png 150w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Red--768x768.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Red--12x12.png 12w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Red--600x600.png 600w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Red--100x100.png 100w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Red-.png 1024w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Red--300x300.png\" class=\"attachment-medium size-medium wp-image-11405\" alt=\"Red\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Red--300x300.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Red--150x150.png 150w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Red--768x768.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Red--12x12.png 12w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Red--600x600.png 600w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Red--100x100.png 100w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Red-.png 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/noscript><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><figcaption class=\"uael-grid-img-content\"><div class=\"uael-grid-img-caption\"><h4 class=\"uael-grid-caption-text\">Red<\/h4><\/div><\/figcaption><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-13\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Rose-.png\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Rose--300x300.png\" class=\"attachment-medium size-medium wp-image-11406 lazyload\" alt=\"Rose\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Rose--300x300.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Rose--150x150.png 150w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Rose--768x768.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Rose--12x12.png 12w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Rose--600x600.png 600w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Rose--100x100.png 100w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Rose-.png 1024w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Rose--300x300.png\" class=\"attachment-medium size-medium wp-image-11406\" alt=\"Rose\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Rose--300x300.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Rose--150x150.png 150w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Rose--768x768.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Rose--12x12.png 12w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Rose--600x600.png 600w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Rose--100x100.png 100w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Rose-.png 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/noscript><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><figcaption class=\"uael-grid-img-content\"><div class=\"uael-grid-img-caption\"><h4 class=\"uael-grid-caption-text\">Rose<\/h4><\/div><\/figcaption><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-14\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Stone-.png\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Stone--300x300.png\" class=\"attachment-medium size-medium wp-image-11407 lazyload\" alt=\"Stone\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Stone--300x300.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Stone--150x150.png 150w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Stone--768x768.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Stone--12x12.png 12w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Stone--600x600.png 600w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Stone--100x100.png 100w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Stone-.png 1024w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Stone--300x300.png\" class=\"attachment-medium size-medium wp-image-11407\" alt=\"Stone\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Stone--300x300.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Stone--150x150.png 150w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Stone--768x768.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Stone--12x12.png 12w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Stone--600x600.png 600w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Stone--100x100.png 100w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Stone-.png 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/noscript><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><figcaption class=\"uael-grid-img-content\"><div class=\"uael-grid-img-caption\"><h4 class=\"uael-grid-caption-text\">Stone<\/h4><\/div><\/figcaption><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-15\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Teal-.png\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Teal--300x300.png\" class=\"attachment-medium size-medium wp-image-11408 lazyload\" alt=\"Teal\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Teal--300x300.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Teal--150x150.png 150w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Teal--768x768.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Teal--12x12.png 12w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Teal--600x600.png 600w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Teal--100x100.png 100w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Teal-.png 1024w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Teal--300x300.png\" class=\"attachment-medium size-medium wp-image-11408\" alt=\"Teal\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Teal--300x300.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Teal--150x150.png 150w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Teal--768x768.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Teal--12x12.png 12w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Teal--600x600.png 600w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Teal--100x100.png 100w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Teal-.png 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/noscript><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><figcaption class=\"uael-grid-img-content\"><div class=\"uael-grid-img-caption\"><h4 class=\"uael-grid-caption-text\">Teal<\/h4><\/div><\/figcaption><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-16\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Yellow-.png\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Yellow--300x300.png\" class=\"attachment-medium size-medium wp-image-11409 lazyload\" alt=\"Yellow\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Yellow--300x300.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Yellow--150x150.png 150w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Yellow--768x768.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Yellow--12x12.png 12w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Yellow--600x600.png 600w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Yellow--100x100.png 100w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Yellow-.png 1024w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Yellow--300x300.png\" class=\"attachment-medium size-medium wp-image-11409\" alt=\"Yellow\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Yellow--300x300.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Yellow--150x150.png 150w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Yellow--768x768.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Yellow--12x12.png 12w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Yellow--600x600.png 600w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Yellow--100x100.png 100w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Yellow-.png 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/noscript><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><figcaption class=\"uael-grid-img-content\"><div class=\"uael-grid-img-caption\"><h4 class=\"uael-grid-caption-text\">Yellow<\/h4><\/div><\/figcaption><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t                    <\/div>\n\t\t        \n                    <div id=\"style-tab\" class=\"clearfix eael-tab-content-item inactive\" data-title-link=\"style-tab\">\n\t\t\t\t        <style>.elementor-10586 .elementor-element.elementor-element-1c09abf:not(.elementor-motion-effects-element-type-background), .elementor-10586 .elementor-element.elementor-element-1c09abf > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:#FFFFFF;}.elementor-10586 .elementor-element.elementor-element-1c09abf > .elementor-container{max-width:1120px;}.elementor-10586 .elementor-element.elementor-element-1c09abf, .elementor-10586 .elementor-element.elementor-element-1c09abf > .elementor-background-overlay{border-radius:10px 10px 10px 10px;}.elementor-10586 .elementor-element.elementor-element-1c09abf{transition:background 0.3s, border 0.3s, border-radius 0.3s, box-shadow 0.3s;margin-top:0px;margin-bottom:0px;padding:40px 40px 40px 40px;}.elementor-10586 .elementor-element.elementor-element-1c09abf > .elementor-background-overlay{transition:background 0.3s, border-radius 0.3s, opacity 0.3s;}.elementor-10586 .elementor-element.elementor-element-95b7414 > .elementor-element-populated{padding:0px 0px 0px 0px;}.elementor-10586 .elementor-element.elementor-element-c955439{padding:0px 0px 0px 0px;}.elementor-10586 .elementor-element.elementor-element-40b91af > .elementor-widget-wrap > .elementor-widget:not(.elementor-widget__width-auto):not(.elementor-widget__width-initial):not(:last-child):not(.elementor-absolute){margin-bottom:10px;}.elementor-10586 .elementor-element.elementor-element-40b91af > .elementor-element-populated{padding:0px 0px 0px 0px;}.elementor-10586 .elementor-element.elementor-element-29a6bac{text-align:left;}.elementor-10586 .elementor-element.elementor-element-29a6bac .elementor-heading-title{font-family:\"Roboto Flex\", Sans-serif;font-size:26px;font-weight:600;}.elementor-10586 .elementor-element.elementor-element-f122f39{text-align:left;font-family:\"Roboto Flex\", Sans-serif;font-size:18px;font-weight:400;text-transform:none;font-style:normal;line-height:26px;color:#616161;}.elementor-10586 .elementor-element.elementor-element-a0689a4{margin-top:40px;margin-bottom:0px;padding:0px 0px 0px 0px;}.elementor-10586 .elementor-element.elementor-element-12c3b77 > .elementor-element-populated{padding:0px 20px 0px 0px;}.elementor-10586 .elementor-element.elementor-element-fe1a875 .elementor-gallery-item__overlay{background-color:#00000042;}.elementor-10586 .elementor-element.elementor-element-fe1a875 .e-gallery-item:hover .elementor-gallery-item__overlay, .elementor-10586 .elementor-element.elementor-element-fe1a875 .e-gallery-item:focus .elementor-gallery-item__overlay{background-color:rgba(0,0,0,0.5);}.elementor-10586 .elementor-element.elementor-element-fe1a875{--image-border-radius:8px;--image-transition-duration:800ms;--overlay-transition-duration:800ms;--content-text-align:center;--content-padding:20px;--content-transition-duration:800ms;--content-transition-delay:800ms;}@media(max-width:1366px){.elementor-10586 .elementor-element.elementor-element-1c09abf, .elementor-10586 .elementor-element.elementor-element-1c09abf > .elementor-background-overlay{border-radius:10px 10px 10px 10px;}.elementor-10586 .elementor-element.elementor-element-1c09abf{padding:40px 40px 40px 40px;}}@media(max-width:1024px){.elementor-10586 .elementor-element.elementor-element-1c09abf{padding:25px 25px 25px 25px;}}@media(max-width:767px){.elementor-10586 .elementor-element.elementor-element-1c09abf{padding:30px 20px 30px 20px;}.elementor-10586 .elementor-element.elementor-element-29a6bac .elementor-heading-title{font-size:26px;line-height:28px;}.elementor-10586 .elementor-element.elementor-element-f122f39{font-size:16px;line-height:24px;}}<\/style>\t\t<div data-elementor-type=\"section\" data-elementor-id=\"10586\" class=\"elementor elementor-10586\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1c09abf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1c09abf\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-95b7414\" data-id=\"95b7414\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c955439 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"c955439\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-40b91af\" data-id=\"40b91af\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29a6bac elementor-widget elementor-widget-heading\" data-id=\"29a6bac\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Stil<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f122f39 elementor-widget elementor-widget-text-editor\" data-id=\"f122f39\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tBaseball caps available in various styles such as standard baseball, snapback, trucker, dad hat, etc.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a0689a4 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"a0689a4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-12c3b77\" data-id=\"12c3b77\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fe1a875 elementor-widget elementor-widget-gallery\" data-id=\"fe1a875\" data-element_type=\"widget\" data-settings=\"{&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:25,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;aspect_ratio&quot;:&quot;4:3&quot;,&quot;overlay_title&quot;:&quot;title&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;gallery_layout&quot;:&quot;grid&quot;,&quot;columns&quot;:4,&quot;columns_tablet&quot;:2,&quot;columns_mobile&quot;:1,&quot;gap_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;link_to&quot;:&quot;file&quot;,&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/5-Panel-Cap-1-1.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"fe1a875\" data-elementor-lightbox-title=\"5 Panel Cap\" data-elementor-lightbox-description=\"5 Panel Cap\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTE0MjcsInVybCI6Imh0dHBzOlwvXC9qb2ludG9wY2FwLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNlwvMDFcLzUtUGFuZWwtQ2FwLTEtMS5wbmciLCJzbGlkZXNob3ciOiJmZTFhODc1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/5-Panel-Cap-1-1.png\" data-width=\"1184\" data-height=\"880\" aria-label=\"5 Panel Cap\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t5 Panel Cap\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/6-Panel-Cap-1-1.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"fe1a875\" data-elementor-lightbox-title=\"6 Panel Cap\" data-elementor-lightbox-description=\"6 Panel Cap\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTE0MjgsInVybCI6Imh0dHBzOlwvXC9qb2ludG9wY2FwLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNlwvMDFcLzYtUGFuZWwtQ2FwLTEtMS5wbmciLCJzbGlkZXNob3ciOiJmZTFhODc1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/6-Panel-Cap-1-1.png\" data-width=\"1184\" data-height=\"880\" aria-label=\"6 Panel Cap\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t6 Panel Cap\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Adjustable-Cap-1-1.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"fe1a875\" data-elementor-lightbox-title=\"Adjustable Cap\" data-elementor-lightbox-description=\"Adjustable Cap\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTE0MjksInVybCI6Imh0dHBzOlwvXC9qb2ludG9wY2FwLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNlwvMDFcL0FkanVzdGFibGUtQ2FwLTEtMS5wbmciLCJzbGlkZXNob3ciOiJmZTFhODc1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Adjustable-Cap-1-1.png\" data-width=\"1184\" data-height=\"880\" aria-label=\"Adjustable Cap\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tAdjustable Cap\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Camouflage-Hat-1-1.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"fe1a875\" data-elementor-lightbox-title=\"Camouflage Hat\" data-elementor-lightbox-description=\"Camouflage Hat\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTE0MzAsInVybCI6Imh0dHBzOlwvXC9qb2ludG9wY2FwLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNlwvMDFcL0NhbW91ZmxhZ2UtSGF0LTEtMS5wbmciLCJzbGlkZXNob3ciOiJmZTFhODc1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Camouflage-Hat-1-1.png\" data-width=\"1184\" data-height=\"880\" aria-label=\"Kamouflagehatt\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tKamouflagehatt\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Classic-Baseball-Cap-1-1.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"fe1a875\" data-elementor-lightbox-title=\"Classic Baseball Cap\" data-elementor-lightbox-description=\"Classic Baseball Cap\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTE0MzEsInVybCI6Imh0dHBzOlwvXC9qb2ludG9wY2FwLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNlwvMDFcL0NsYXNzaWMtQmFzZWJhbGwtQ2FwLTEtMS5wbmciLCJzbGlkZXNob3ciOiJmZTFhODc1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Classic-Baseball-Cap-1-1.png\" data-width=\"1184\" data-height=\"880\" aria-label=\"Klassisk basebollkeps\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tKlassisk basebollkeps\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Dad-Hat-1-1.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"fe1a875\" data-elementor-lightbox-title=\"Dad Hat\" data-elementor-lightbox-description=\"Dad Hat\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTE0MzIsInVybCI6Imh0dHBzOlwvXC9qb2ludG9wY2FwLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNlwvMDFcL0RhZC1IYXQtMS0xLnBuZyIsInNsaWRlc2hvdyI6ImZlMWE4NzUifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Dad-Hat-1-1.png\" data-width=\"1184\" data-height=\"880\" aria-label=\"Pappa hatt\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tPappa hatt\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Fitted-Cap-1-1.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"fe1a875\" data-elementor-lightbox-title=\"Fitted Cap\" data-elementor-lightbox-description=\"Fitted Cap\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTE0MzMsInVybCI6Imh0dHBzOlwvXC9qb2ludG9wY2FwLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNlwvMDFcL0ZpdHRlZC1DYXAtMS0xLnBuZyIsInNsaWRlc2hvdyI6ImZlMWE4NzUifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Fitted-Cap-1-1.png\" data-width=\"1184\" data-height=\"880\" aria-label=\"Fitted Cap\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tFitted Cap\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Snapback-Cap-1-1.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"fe1a875\" data-elementor-lightbox-title=\"Snapback Cap\" data-elementor-lightbox-description=\"Snapback Cap\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTE0MzQsInVybCI6Imh0dHBzOlwvXC9qb2ludG9wY2FwLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNlwvMDFcL1NuYXBiYWNrLUNhcC0xLTEucG5nIiwic2xpZGVzaG93IjoiZmUxYTg3NSJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Snapback-Cap-1-1.png\" data-width=\"1184\" data-height=\"880\" aria-label=\"Snapback keps\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tSnapback keps\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Structured-Cap-1-1.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"fe1a875\" data-elementor-lightbox-title=\"Structured Cap\" data-elementor-lightbox-description=\"Structured Cap\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTE0MzUsInVybCI6Imh0dHBzOlwvXC9qb2ludG9wY2FwLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNlwvMDFcL1N0cnVjdHVyZWQtQ2FwLTEtMS5wbmciLCJzbGlkZXNob3ciOiJmZTFhODc1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Structured-Cap-1-1.png\" data-width=\"1184\" data-height=\"880\" aria-label=\"Structured Cap\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tStructured Cap\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Trucker-Hat-1-1.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"fe1a875\" data-elementor-lightbox-title=\"Trucker Hat\" data-elementor-lightbox-description=\"Trucker Hat\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTE0MzYsInVybCI6Imh0dHBzOlwvXC9qb2ludG9wY2FwLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNlwvMDFcL1RydWNrZXItSGF0LTEtMS5wbmciLCJzbGlkZXNob3ciOiJmZTFhODc1In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Trucker-Hat-1-1.png\" data-width=\"1184\" data-height=\"880\" aria-label=\"Truckerhatt\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tTruckerhatt\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Unstructured-Cap-1-1.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"fe1a875\" data-elementor-lightbox-title=\"Unstructured Cap\" data-elementor-lightbox-description=\"Unstructured Cap\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTE0MzcsInVybCI6Imh0dHBzOlwvXC9qb2ludG9wY2FwLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNlwvMDFcL1Vuc3RydWN0dXJlZC1DYXAtMS0xLnBuZyIsInNsaWRlc2hvdyI6ImZlMWE4NzUifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Unstructured-Cap-1-1.png\" data-width=\"1184\" data-height=\"880\" aria-label=\"Unstructured Cap\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tUnstructured Cap\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t                    <\/div>\n\t\t        \n                    <div id=\"packaging-delivery-tab\" class=\"clearfix eael-tab-content-item inactive\" data-title-link=\"packaging-delivery-tab\">\n\t\t\t\t        <style>.elementor-10585 .elementor-element.elementor-element-1c09abf:not(.elementor-motion-effects-element-type-background), .elementor-10585 .elementor-element.elementor-element-1c09abf > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:#FFFFFF;}.elementor-10585 .elementor-element.elementor-element-1c09abf > .elementor-container{max-width:1120px;}.elementor-10585 .elementor-element.elementor-element-1c09abf, .elementor-10585 .elementor-element.elementor-element-1c09abf > .elementor-background-overlay{border-radius:10px 10px 10px 10px;}.elementor-10585 .elementor-element.elementor-element-1c09abf{transition:background 0.3s, border 0.3s, border-radius 0.3s, box-shadow 0.3s;margin-top:0px;margin-bottom:0px;padding:40px 40px 40px 40px;}.elementor-10585 .elementor-element.elementor-element-1c09abf > .elementor-background-overlay{transition:background 0.3s, border-radius 0.3s, opacity 0.3s;}.elementor-10585 .elementor-element.elementor-element-95b7414 > .elementor-element-populated{padding:0px 0px 0px 0px;}.elementor-10585 .elementor-element.elementor-element-c955439{padding:0px 0px 0px 0px;}.elementor-10585 .elementor-element.elementor-element-40b91af > .elementor-widget-wrap > .elementor-widget:not(.elementor-widget__width-auto):not(.elementor-widget__width-initial):not(:last-child):not(.elementor-absolute){margin-bottom:10px;}.elementor-10585 .elementor-element.elementor-element-40b91af > .elementor-element-populated{padding:0px 0px 0px 0px;}.elementor-10585 .elementor-element.elementor-element-29a6bac{text-align:left;}.elementor-10585 .elementor-element.elementor-element-29a6bac .elementor-heading-title{font-family:\"Roboto Flex\", Sans-serif;font-size:26px;font-weight:600;}.elementor-10585 .elementor-element.elementor-element-f122f39{text-align:left;font-family:\"Roboto Flex\", Sans-serif;font-size:18px;font-weight:400;text-transform:none;font-style:normal;line-height:26px;color:#616161;}.elementor-10585 .elementor-element.elementor-element-196c9ae{padding:20px 0px 0px 0px;}.elementor-10585 .elementor-element.elementor-element-6011591 > .elementor-element-populated{padding:0px 10px 0px 0px;}.elementor-10585 .elementor-element.elementor-element-ee8b8e3 .elementor-gallery-item__overlay{background-color:#0C070729;}.elementor-10585 .elementor-element.elementor-element-ee8b8e3 .e-gallery-item:hover .elementor-gallery-item__overlay, .elementor-10585 .elementor-element.elementor-element-ee8b8e3 .e-gallery-item:focus .elementor-gallery-item__overlay{background-color:rgba(0,0,0,0.5);}.elementor-10585 .elementor-element.elementor-element-ee8b8e3{--image-border-radius:8px;--image-transition-duration:800ms;--overlay-transition-duration:800ms;--content-text-align:center;--content-padding:20px;--content-transition-duration:800ms;--content-transition-delay:800ms;}@media(max-width:1366px){.elementor-10585 .elementor-element.elementor-element-1c09abf, .elementor-10585 .elementor-element.elementor-element-1c09abf > .elementor-background-overlay{border-radius:10px 10px 10px 10px;}.elementor-10585 .elementor-element.elementor-element-1c09abf{padding:40px 40px 40px 40px;}}@media(max-width:1024px){.elementor-10585 .elementor-element.elementor-element-1c09abf{padding:25px 25px 25px 25px;}}@media(max-width:767px){.elementor-10585 .elementor-element.elementor-element-1c09abf{padding:30px 0px 30px 0px;}.elementor-10585 .elementor-element.elementor-element-29a6bac .elementor-heading-title{font-size:26px;line-height:28px;}.elementor-10585 .elementor-element.elementor-element-f122f39{font-size:16px;line-height:24px;}}<\/style>\t\t<div data-elementor-type=\"section\" data-elementor-id=\"10585\" class=\"elementor elementor-10585\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1c09abf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1c09abf\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-95b7414\" data-id=\"95b7414\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c955439 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"c955439\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-40b91af\" data-id=\"40b91af\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29a6bac elementor-widget elementor-widget-heading\" data-id=\"29a6bac\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Packaging &amp; Delivery<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f122f39 elementor-widget elementor-widget-text-editor\" data-id=\"f122f39\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tOptions include standard poly bag, custom box, branded packaging, or eco-friendly solutions.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-196c9ae elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"196c9ae\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6011591\" data-id=\"6011591\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ee8b8e3 elementor-widget elementor-widget-gallery\" data-id=\"ee8b8e3\" data-element_type=\"widget\" data-settings=\"{&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:25,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;aspect_ratio&quot;:&quot;4:3&quot;,&quot;overlay_title&quot;:&quot;title&quot;,&quot;columns&quot;:3,&quot;lazyload&quot;:&quot;yes&quot;,&quot;gallery_layout&quot;:&quot;grid&quot;,&quot;columns_tablet&quot;:2,&quot;columns_mobile&quot;:1,&quot;gap_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;link_to&quot;:&quot;file&quot;,&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Branded-Packaging-1-1.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ee8b8e3\" data-elementor-lightbox-title=\"Branded Packaging\" data-elementor-lightbox-description=\"Branded Packaging\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTE0NDcsInVybCI6Imh0dHBzOlwvXC9qb2ludG9wY2FwLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNlwvMDFcL0JyYW5kZWQtUGFja2FnaW5nLTEtMS5wbmciLCJzbGlkZXNob3ciOiJlZThiOGUzIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Branded-Packaging-1-1.png\" data-width=\"1184\" data-height=\"880\" aria-label=\"Branded Packaging\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tBranded Packaging\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Bulk-Carton-Packing-1-1.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ee8b8e3\" data-elementor-lightbox-title=\"Bulk Carton Packing\" data-elementor-lightbox-description=\"Bulk Carton Packing\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTE0NDgsInVybCI6Imh0dHBzOlwvXC9qb2ludG9wY2FwLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNlwvMDFcL0J1bGstQ2FydG9uLVBhY2tpbmctMS0xLnBuZyIsInNsaWRlc2hvdyI6ImVlOGI4ZTMifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Bulk-Carton-Packing-1-1.png\" data-width=\"1184\" data-height=\"880\" aria-label=\"Bulk Carton Packing\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tBulk Carton Packing\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Custom-Printed-Box-1-1.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ee8b8e3\" data-elementor-lightbox-title=\"Custom Printed Box\" data-elementor-lightbox-description=\"Custom Printed Box\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTE0NDksInVybCI6Imh0dHBzOlwvXC9qb2ludG9wY2FwLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNlwvMDFcL0N1c3RvbS1QcmludGVkLUJveC0xLTEucG5nIiwic2xpZGVzaG93IjoiZWU4YjhlMyJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Custom-Printed-Box-1-1.png\" data-width=\"1184\" data-height=\"880\" aria-label=\"Custom Printed Box\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tCustom Printed Box\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Eco-friendly-Packaging-1-1.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ee8b8e3\" data-elementor-lightbox-title=\"Eco friendly Packaging\" data-elementor-lightbox-description=\"Eco friendly Packaging\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTE0NTAsInVybCI6Imh0dHBzOlwvXC9qb2ludG9wY2FwLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNlwvMDFcL0Vjby1mcmllbmRseS1QYWNrYWdpbmctMS0xLnBuZyIsInNsaWRlc2hvdyI6ImVlOGI4ZTMifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Eco-friendly-Packaging-1-1.png\" data-width=\"1184\" data-height=\"880\" aria-label=\"Eco friendly Packaging\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tEco friendly Packaging\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Individual-Polybag-.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ee8b8e3\" data-elementor-lightbox-title=\"Individual Polybag\" data-elementor-lightbox-description=\"Individual Polybag\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTE0NTEsInVybCI6Imh0dHBzOlwvXC9qb2ludG9wY2FwLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNlwvMDFcL0luZGl2aWR1YWwtUG9seWJhZy0ucG5nIiwic2xpZGVzaG93IjoiZWU4YjhlMyJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Individual-Polybag-.png\" data-width=\"1184\" data-height=\"880\" aria-label=\"Individual Polybag\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tIndividual Polybag\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Polybag-with-Inner-Support-.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ee8b8e3\" data-elementor-lightbox-title=\"Polybag with Inner Support\" data-elementor-lightbox-description=\"Polybag with Inner Support\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTE0NTIsInVybCI6Imh0dHBzOlwvXC9qb2ludG9wY2FwLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNlwvMDFcL1BvbHliYWctd2l0aC1Jbm5lci1TdXBwb3J0LS5wbmciLCJzbGlkZXNob3ciOiJlZThiOGUzIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/Polybag-with-Inner-Support-.png\" data-width=\"1184\" data-height=\"880\" aria-label=\"Polybag with Inner Support\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tPolybag with Inner Support\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t                    <\/div>\n\t\t                    <\/div>\n        <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3b6b330 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3b6b330\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-52f0f28\" data-id=\"52f0f28\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c004675 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c004675\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-f35790c\" data-id=\"f35790c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8725177 elementor-widget elementor-widget-heading\" data-id=\"8725177\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Simple Process<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bc17031 elementor-widget elementor-widget-heading\" data-id=\"bc17031\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Form Concept to Delivery<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a65de1d elementor-widget elementor-widget-text-editor\" data-id=\"a65de1d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tFour simple steps to bring your custom headwear to life. We handle the<br>complexity so you don&#8217;t have to.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a081db7 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"a081db7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-564b9b9\" data-id=\"564b9b9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b42e60 st-box elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"1b42e60\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1184\" height=\"880\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_tech_pack_18d56064.png\" class=\"attachment-full size-full wp-image-11580 lazyload\" alt=\"real tech pack 18d56064\" title=\"real tech pack 18d56064  JoinTop | Custom Hat Manufacturer  Supplier | OEM  ODM Headwear Factory\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_tech_pack_18d56064.png 1184w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_tech_pack_18d56064-300x223.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_tech_pack_18d56064-1024x761.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_tech_pack_18d56064-768x571.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_tech_pack_18d56064-16x12.png 16w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_tech_pack_18d56064-600x446.png 600w\" data-sizes=\"(max-width: 1184px) 100vw, 1184px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1184px; --smush-placeholder-aspect-ratio: 1184\/880;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1184\" height=\"880\" src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_tech_pack_18d56064.png\" class=\"attachment-full size-full wp-image-11580\" alt=\"real tech pack 18d56064\" title=\"real tech pack 18d56064  JoinTop | Custom Hat Manufacturer  Supplier | OEM  ODM Headwear Factory\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_tech_pack_18d56064.png 1184w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_tech_pack_18d56064-300x223.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_tech_pack_18d56064-1024x761.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_tech_pack_18d56064-768x571.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_tech_pack_18d56064-16x12.png 16w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_tech_pack_18d56064-600x446.png 600w\" sizes=\"(max-width: 1184px) 100vw, 1184px\" \/><\/noscript><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Send Tech Pack<\/h3><p class=\"elementor-image-box-description\">Share your design files, reference\nimages, or just an idea. We'll\nquide you through the specs.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-e9f21bd\" data-id=\"e9f21bd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ae1490 elementor-hidden-mobile elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"1ae1490\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"icon icon-right-arrow\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-ad277bc\" data-id=\"ad277bc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c824b6 nd-box elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"6c824b6\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1184\" height=\"880\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_mockup_20938475.png\" class=\"attachment-full size-full wp-image-11577 lazyload\" alt=\"real mockup 20938475\" title=\"real mockup 20938475  JoinTop | Custom Hat Manufacturer  Supplier | OEM  ODM Headwear Factory\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_mockup_20938475.png 1184w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_mockup_20938475-300x223.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_mockup_20938475-1024x761.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_mockup_20938475-768x571.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_mockup_20938475-16x12.png 16w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_mockup_20938475-600x446.png 600w\" data-sizes=\"(max-width: 1184px) 100vw, 1184px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1184px; --smush-placeholder-aspect-ratio: 1184\/880;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1184\" height=\"880\" src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_mockup_20938475.png\" class=\"attachment-full size-full wp-image-11577\" alt=\"real mockup 20938475\" title=\"real mockup 20938475  JoinTop | Custom Hat Manufacturer  Supplier | OEM  ODM Headwear Factory\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_mockup_20938475.png 1184w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_mockup_20938475-300x223.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_mockup_20938475-1024x761.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_mockup_20938475-768x571.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_mockup_20938475-16x12.png 16w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_mockup_20938475-600x446.png 600w\" sizes=\"(max-width: 1184px) 100vw, 1184px\" \/><\/noscript><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Digital Mockup Free<\/h3><p class=\"elementor-image-box-description\">Receive professional 3D within 24 hours. Refine until perfect \u2014 unlimited revisions.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-7c4f236\" data-id=\"7c4f236\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-93dbc15 elementor-hidden-mobile elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"93dbc15\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"icon icon-right-arrow\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-db454fc\" data-id=\"db454fc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dad7ef7 rd-box elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"dad7ef7\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1184\" height=\"880\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_sample_96571983.png\" class=\"attachment-full size-full wp-image-11578 lazyload\" alt=\"real sample 96571983\" title=\"real sample 96571983  JoinTop | Custom Hat Manufacturer  Supplier | OEM  ODM Headwear Factory\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_sample_96571983.png 1184w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_sample_96571983-300x223.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_sample_96571983-1024x761.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_sample_96571983-768x571.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_sample_96571983-16x12.png 16w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_sample_96571983-600x446.png 600w\" data-sizes=\"(max-width: 1184px) 100vw, 1184px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1184px; --smush-placeholder-aspect-ratio: 1184\/880;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1184\" height=\"880\" src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_sample_96571983.png\" class=\"attachment-full size-full wp-image-11578\" alt=\"real sample 96571983\" title=\"real sample 96571983  JoinTop | Custom Hat Manufacturer  Supplier | OEM  ODM Headwear Factory\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_sample_96571983.png 1184w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_sample_96571983-300x223.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_sample_96571983-1024x761.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_sample_96571983-768x571.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_sample_96571983-16x12.png 16w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_sample_96571983-600x446.png 600w\" sizes=\"(max-width: 1184px) 100vw, 1184px\" \/><\/noscript><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Sample Production<\/h3><p class=\"elementor-image-box-description\">We produce physical samples for your approval. Touch, feel and verify quality before bulk.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9fbd78f elementor-hidden-mobile elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"9fbd78f\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"icon icon-download-arrow\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c28cd07 elementor-section-full_width elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"c28cd07\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-d3bd26a\" data-id=\"d3bd26a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-ca234ad\" data-id=\"ca234ad\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-95e8bcf five-box elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"95e8bcf\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1184\" height=\"880\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_shipping_ec92d23e.png\" class=\"attachment-full size-full wp-image-11579 lazyload\" alt=\"real shipping ec92d23e\" title=\"real shipping ec92d23e  JoinTop | Custom Hat Manufacturer  Supplier | OEM  ODM Headwear Factory\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_shipping_ec92d23e.png 1184w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_shipping_ec92d23e-300x223.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_shipping_ec92d23e-1024x761.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_shipping_ec92d23e-768x571.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_shipping_ec92d23e-16x12.png 16w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_shipping_ec92d23e-600x446.png 600w\" data-sizes=\"(max-width: 1184px) 100vw, 1184px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1184px; --smush-placeholder-aspect-ratio: 1184\/880;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1184\" height=\"880\" src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_shipping_ec92d23e.png\" class=\"attachment-full size-full wp-image-11579\" alt=\"real shipping ec92d23e\" title=\"real shipping ec92d23e  JoinTop | Custom Hat Manufacturer  Supplier | OEM  ODM Headwear Factory\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_shipping_ec92d23e.png 1184w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_shipping_ec92d23e-300x223.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_shipping_ec92d23e-1024x761.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_shipping_ec92d23e-768x571.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_shipping_ec92d23e-16x12.png 16w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_shipping_ec92d23e-600x446.png 600w\" sizes=\"(max-width: 1184px) 100vw, 1184px\" \/><\/noscript><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Shipping &amp; Delivery<\/h3><p class=\"elementor-image-box-description\">Express, air, or sea freight. Shipping to destinations worldwide.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-c263881\" data-id=\"c263881\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-85ea8ab elementor-hidden-mobile elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"85ea8ab\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"icon icon-left-arrow\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-6f43205\" data-id=\"6f43205\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bc13db5 th-box elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"bc13db5\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1184\" height=\"880\" data-src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_bulk_99533505.png\" class=\"attachment-full size-full wp-image-11576 lazyload\" alt=\"real bulk 99533505\" title=\"real bulk 99533505  JoinTop | Custom Hat Manufacturer  Supplier | OEM  ODM Headwear Factory\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_bulk_99533505.png 1184w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_bulk_99533505-300x223.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_bulk_99533505-1024x761.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_bulk_99533505-768x571.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_bulk_99533505-16x12.png 16w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_bulk_99533505-600x446.png 600w\" data-sizes=\"(max-width: 1184px) 100vw, 1184px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1184px; --smush-placeholder-aspect-ratio: 1184\/880;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1184\" height=\"880\" src=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_bulk_99533505.png\" class=\"attachment-full size-full wp-image-11576\" alt=\"real bulk 99533505\" title=\"real bulk 99533505  JoinTop | Custom Hat Manufacturer  Supplier | OEM  ODM Headwear Factory\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_bulk_99533505.png 1184w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_bulk_99533505-300x223.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_bulk_99533505-1024x761.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_bulk_99533505-768x571.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_bulk_99533505-16x12.png 16w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/real_bulk_99533505-600x446.png 600w\" sizes=\"(max-width: 1184px) 100vw, 1184px\" \/><\/noscript><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Bulk Manufacturing<\/h3><p class=\"elementor-image-box-description\">Full production with sit QC. Flexible shipping options to any destination worldwide.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-07c6b80\" data-id=\"07c6b80\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8780384 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8780384\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a335bfd\" data-id=\"a335bfd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1d61147 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1d61147\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-638315b\" data-id=\"638315b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a3814c elementor-widget elementor-widget-heading\" data-id=\"1a3814c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Frequently Asked Question<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5445523 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5445523\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-8b2f918\" data-id=\"8b2f918\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-258c4a9 elementor-widget elementor-widget-elementskit-accordion\" data-id=\"258c4a9\" data-element_type=\"widget\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a044a2e941e6\">\n\n            \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-258c4a9\">\n                        <a href=\"#collapse-925b0186a044a2e941e6\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-925b0186a044a2e941e6\" aria-expanded=\"false\" aria-controls=\"Collapse-925b0186a044a2e941e6\">\n                            \n                            <span class=\"ekit-accordion-title\">What customization options are available for custom baseball caps?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-925b0186a044a2e941e6\" class=\"collapse\" aria-labelledby=\"primaryHeading-0-258c4a9\" data-parent=\"#accordion-6a044a2e941e6\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>We offer full customization, including cap styles, fabrics, colors, logo techniques, logo placement, closure types, and packaging. You can customize every detail to match your brand identity.<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11305 size-full lazyload\" data-src=\"http:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_customization_77a007fd.png\" alt=\"\" width=\"1392\" height=\"752\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_customization_77a007fd.png 1392w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_customization_77a007fd-300x162.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_customization_77a007fd-1024x553.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_customization_77a007fd-768x415.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_customization_77a007fd-18x10.png 18w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_customization_77a007fd-1320x713.png 1320w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_customization_77a007fd-600x324.png 600w\" data-sizes=\"(max-width: 1392px) 100vw, 1392px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1392px; --smush-placeholder-aspect-ratio: 1392\/752;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11305 size-full\" src=\"http:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_customization_77a007fd.png\" alt=\"\" width=\"1392\" height=\"752\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_customization_77a007fd.png 1392w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_customization_77a007fd-300x162.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_customization_77a007fd-1024x553.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_customization_77a007fd-768x415.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_customization_77a007fd-18x10.png 18w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_customization_77a007fd-1320x713.png 1320w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_customization_77a007fd-600x324.png 600w\" sizes=\"(max-width: 1392px) 100vw, 1392px\" \/><\/noscript><\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-258c4a9\">\n                        <a href=\"#collapse-b972b816a044a2e941e6\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-b972b816a044a2e941e6\" aria-expanded=\"false\" aria-controls=\"Collapse-b972b816a044a2e941e6\">\n                            \n                            <span class=\"ekit-accordion-title\">What types of baseball caps can you manufacture?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-b972b816a044a2e941e6\" class=\"collapse\" aria-labelledby=\"primaryHeading-1-258c4a9\" data-parent=\"#accordion-6a044a2e941e6\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>We manufacture a wide range of styles, including baseball caps, dad hats, trucker caps, snapback caps, fitted caps, and custom designs based on your reference samples or drawings.<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11321 size-full lazyload\" data-src=\"http:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_cap_types_53920a1b.png\" alt=\"\" width=\"1392\" height=\"752\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_cap_types_53920a1b.png 1392w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_cap_types_53920a1b-300x162.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_cap_types_53920a1b-1024x553.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_cap_types_53920a1b-768x415.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_cap_types_53920a1b-18x10.png 18w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_cap_types_53920a1b-1320x713.png 1320w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_cap_types_53920a1b-600x324.png 600w\" data-sizes=\"(max-width: 1392px) 100vw, 1392px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1392px; --smush-placeholder-aspect-ratio: 1392\/752;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11321 size-full\" src=\"http:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_cap_types_53920a1b.png\" alt=\"\" width=\"1392\" height=\"752\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_cap_types_53920a1b.png 1392w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_cap_types_53920a1b-300x162.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_cap_types_53920a1b-1024x553.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_cap_types_53920a1b-768x415.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_cap_types_53920a1b-18x10.png 18w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_cap_types_53920a1b-1320x713.png 1320w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_cap_types_53920a1b-600x324.png 600w\" sizes=\"(max-width: 1392px) 100vw, 1392px\" \/><\/noscript><\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-2-258c4a9\">\n                        <a href=\"#collapse-36c57036a044a2e941e6\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-36c57036a044a2e941e6\" aria-expanded=\"false\" aria-controls=\"Collapse-36c57036a044a2e941e6\">\n                            \n                            <span class=\"ekit-accordion-title\">What is your minimum order quantity (MOQ)?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-36c57036a044a2e941e6\" class=\"collapse\" aria-labelledby=\"primaryHeading-2-258c4a9\" data-parent=\"#accordion-6a044a2e941e6\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Our standard MOQ starts from 100\u2013200 pieces per design, depending on the style and customization requirements. For new customers, sample orders are available for quality evaluation.<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11328 size-full lazyload\" data-src=\"http:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_moq_d189542b.png\" alt=\"\" width=\"1392\" height=\"752\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_moq_d189542b.png 1392w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_moq_d189542b-300x162.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_moq_d189542b-1024x553.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_moq_d189542b-768x415.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_moq_d189542b-18x10.png 18w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_moq_d189542b-1320x713.png 1320w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_moq_d189542b-600x324.png 600w\" data-sizes=\"(max-width: 1392px) 100vw, 1392px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1392px; --smush-placeholder-aspect-ratio: 1392\/752;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11328 size-full\" src=\"http:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_moq_d189542b.png\" alt=\"\" width=\"1392\" height=\"752\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_moq_d189542b.png 1392w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_moq_d189542b-300x162.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_moq_d189542b-1024x553.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_moq_d189542b-768x415.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_moq_d189542b-18x10.png 18w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_moq_d189542b-1320x713.png 1320w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_moq_d189542b-600x324.png 600w\" sizes=\"(max-width: 1392px) 100vw, 1392px\" \/><\/noscript><\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-3-258c4a9\">\n                        <a href=\"#collapse-6e4a91e6a044a2e941e6\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-6e4a91e6a044a2e941e6\" aria-expanded=\"false\" aria-controls=\"Collapse-6e4a91e6a044a2e941e6\">\n                            \n                            <span class=\"ekit-accordion-title\">Can I order a sample before placing a bulk order?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-6e4a91e6a044a2e941e6\" class=\"collapse\" aria-labelledby=\"primaryHeading-3-258c4a9\" data-parent=\"#accordion-6a044a2e941e6\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Yes. We provide custom samples so you can check the fit, materials, and logo details before mass production. Sample lead time is usually 5\u20137 days.<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-11335 size-full lazyload\" data-src=\"http:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_sample_7b332cfe.png\" alt=\"\" width=\"1392\" height=\"752\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_sample_7b332cfe.png 1392w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_sample_7b332cfe-300x162.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_sample_7b332cfe-1024x553.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_sample_7b332cfe-768x415.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_sample_7b332cfe-18x10.png 18w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_sample_7b332cfe-1320x713.png 1320w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_sample_7b332cfe-600x324.png 600w\" data-sizes=\"(max-width: 1392px) 100vw, 1392px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1392px; --smush-placeholder-aspect-ratio: 1392\/752;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-11335 size-full\" src=\"http:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_sample_7b332cfe.png\" alt=\"\" width=\"1392\" height=\"752\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_sample_7b332cfe.png 1392w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_sample_7b332cfe-300x162.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_sample_7b332cfe-1024x553.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_sample_7b332cfe-768x415.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_sample_7b332cfe-18x10.png 18w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_sample_7b332cfe-1320x713.png 1320w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_sample_7b332cfe-600x324.png 600w\" sizes=\"(max-width: 1392px) 100vw, 1392px\" \/><\/noscript><\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-4-258c4a9\">\n                        <a href=\"#collapse-fd2486c6a044a2e941e6\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-fd2486c6a044a2e941e6\" aria-expanded=\"false\" aria-controls=\"Collapse-fd2486c6a044a2e941e6\">\n                            \n                            <span class=\"ekit-accordion-title\">What is the production lead time for custom baseball caps?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-fd2486c6a044a2e941e6\" class=\"collapse\" aria-labelledby=\"primaryHeading-4-258c4a9\" data-parent=\"#accordion-6a044a2e941e6\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Sample production usually takes 5\u20137 days. Bulk production typically takes 15\u201325 days after sample approval, depending on order quantity and customization complexity.<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-11348 size-full lazyload\" data-src=\"http:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_production_472370f1.png\" alt=\"\" width=\"1392\" height=\"752\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_production_472370f1.png 1392w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_production_472370f1-300x162.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_production_472370f1-1024x553.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_production_472370f1-768x415.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_production_472370f1-18x10.png 18w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_production_472370f1-1320x713.png 1320w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_production_472370f1-600x324.png 600w\" data-sizes=\"(max-width: 1392px) 100vw, 1392px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1392px; --smush-placeholder-aspect-ratio: 1392\/752;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-11348 size-full\" src=\"http:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_production_472370f1.png\" alt=\"\" width=\"1392\" height=\"752\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_production_472370f1.png 1392w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_production_472370f1-300x162.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_production_472370f1-1024x553.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_production_472370f1-768x415.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_production_472370f1-18x10.png 18w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_production_472370f1-1320x713.png 1320w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_production_472370f1-600x324.png 600w\" sizes=\"(max-width: 1392px) 100vw, 1392px\" \/><\/noscript><\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-5-258c4a9\">\n                        <a href=\"#collapse-accfa126a044a2e941e6\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-accfa126a044a2e941e6\" aria-expanded=\"false\" aria-controls=\"Collapse-accfa126a044a2e941e6\">\n                            \n                            <span class=\"ekit-accordion-title\">How do you ensure consistent quality for bulk orders?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-accfa126a044a2e941e6\" class=\"collapse\" aria-labelledby=\"primaryHeading-5-258c4a9\" data-parent=\"#accordion-6a044a2e941e6\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Our experienced workforce follows standardized production workflows with quality checks at every stage, from material inspection to final packaging, ensuring consistent quality across all units.<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-11349 size-full lazyload\" data-src=\"http:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_quality_e63568f9.png\" alt=\"\" width=\"1392\" height=\"752\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_quality_e63568f9.png 1392w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_quality_e63568f9-300x162.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_quality_e63568f9-1024x553.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_quality_e63568f9-768x415.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_quality_e63568f9-18x10.png 18w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_quality_e63568f9-1320x713.png 1320w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_quality_e63568f9-600x324.png 600w\" data-sizes=\"(max-width: 1392px) 100vw, 1392px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1392px; --smush-placeholder-aspect-ratio: 1392\/752;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-11349 size-full\" src=\"http:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_quality_e63568f9.png\" alt=\"\" width=\"1392\" height=\"752\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_quality_e63568f9.png 1392w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_quality_e63568f9-300x162.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_quality_e63568f9-1024x553.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_quality_e63568f9-768x415.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_quality_e63568f9-18x10.png 18w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_quality_e63568f9-1320x713.png 1320w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_quality_e63568f9-600x324.png 600w\" sizes=\"(max-width: 1392px) 100vw, 1392px\" \/><\/noscript><\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-6-258c4a9\">\n                        <a href=\"#collapse-36f4d826a044a2e941e6\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-36f4d826a044a2e941e6\" aria-expanded=\"false\" aria-controls=\"Collapse-36f4d826a044a2e941e6\">\n                            \n                            <span class=\"ekit-accordion-title\">What shipping methods do you offer?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-36f4d826a044a2e941e6\" class=\"collapse\" aria-labelledby=\"primaryHeading-6-258c4a9\" data-parent=\"#accordion-6a044a2e941e6\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>We support air freight, sea freight, express delivery, and can work with your own forwarder. Shipping options are recommended based on your timeline and destination.<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11350 size-full lazyload\" data-src=\"http:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_shipping_fbb448c2.png\" alt=\"\" width=\"1392\" height=\"752\" data-srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_shipping_fbb448c2.png 1392w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_shipping_fbb448c2-300x162.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_shipping_fbb448c2-1024x553.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_shipping_fbb448c2-768x415.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_shipping_fbb448c2-18x10.png 18w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_shipping_fbb448c2-1320x713.png 1320w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_shipping_fbb448c2-600x324.png 600w\" data-sizes=\"(max-width: 1392px) 100vw, 1392px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1392px; --smush-placeholder-aspect-ratio: 1392\/752;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11350 size-full\" src=\"http:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_shipping_fbb448c2.png\" alt=\"\" width=\"1392\" height=\"752\" srcset=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_shipping_fbb448c2.png 1392w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_shipping_fbb448c2-300x162.png 300w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_shipping_fbb448c2-1024x553.png 1024w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_shipping_fbb448c2-768x415.png 768w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_shipping_fbb448c2-18x10.png 18w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_shipping_fbb448c2-1320x713.png 1320w, https:\/\/jointopcap.com\/wp-content\/uploads\/2026\/01\/faq_shipping_fbb448c2-600x324.png 600w\" sizes=\"(max-width: 1392px) 100vw, 1392px\" \/><\/noscript><\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                                        <\/div>\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7f74d3c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7f74d3c\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c498de1\" data-id=\"c498de1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8120567 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8120567\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-cd50a91\" data-id=\"cd50a91\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-733b927 elementor-widget elementor-widget-heading\" data-id=\"733b927\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Need Help Design?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36f48f1 elementor-widget elementor-widget-text-editor\" data-id=\"36f48f1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Download our Free Template And Guidline<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e41cef4 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"e41cef4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-92f3288 grid-how\" data-id=\"92f3288\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-0029cce\" data-id=\"0029cce\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31d2454 elementor-view-stacked elementor-position-left elementor-shape-circle elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"31d2454\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-file-image\" viewbox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M369.9 97.9L286 14C277 5 264.8-.1 252.1-.1H48C21.5 0 0 21.5 0 48v416c0 26.5 21.5 48 48 48h288c26.5 0 48-21.5 48-48V131.9c0-12.7-5.1-25-14.1-34zM332.1 128H256V51.9l76.1 76.1zM48 464V48h160v104c0 13.3 10.7 24 24 24h104v288H48zm32-48h224V288l-23.5-23.5c-4.7-4.7-12.3-4.7-17 0L176 352l-39.5-39.5c-4.7-4.7-12.3-4.7-17 0L80 352v64zm48-240c-26.5 0-48 21.5-48 48s21.5 48 48 48 48-21.5 48-48-21.5-48-48-48z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tBlank Cap Template\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tWe create a digital mockup. Upon approval, we produce a physical \t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-916fd74 elementor-align-justify elementor-widget-mobile__width-initial elementor-widget elementor-widget-button\" data-id=\"916fd74\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-download\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M216 0h80c13.3 0 24 10.7 24 24v168h87.7c17.8 0 26.7 21.5 14.1 34.1L269.7 378.3c-7.5 7.5-19.8 7.5-27.3 0L90.1 226.1c-12.6-12.6-3.7-34.1 14.1-34.1H192V24c0-13.3 10.7-24 24-24zm296 376v112c0 13.3-10.7 24-24 24H24c-13.3 0-24-10.7-24-24V376c0-13.3 10.7-24 24-24h146.7l49 49c20.1 20.1 52.5 20.1 72.6 0l49-49H488c13.3 0 24 10.7 24 24zm-124 88c0-11-9-20-20-20s-20 9-20 20 9 20 20 20 20-9 20-20zm64 0c0-11-9-20-20-20s-20 9-20 20 9 20 20 20 20-9 20-20z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Download Free<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-74e349a\" data-id=\"74e349a\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-da1b447 elementor-view-stacked elementor-position-left elementor-shape-circle elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"da1b447\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-file-alt\" viewbox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288 248v28c0 6.6-5.4 12-12 12H108c-6.6 0-12-5.4-12-12v-28c0-6.6 5.4-12 12-12h168c6.6 0 12 5.4 12 12zm-12 72H108c-6.6 0-12 5.4-12 12v28c0 6.6 5.4 12 12 12h168c6.6 0 12-5.4 12-12v-28c0-6.6-5.4-12-12-12zm108-188.1V464c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V48C0 21.5 21.5 0 48 0h204.1C264.8 0 277 5.1 286 14.1L369.9 98c9 8.9 14.1 21.2 14.1 33.9zm-128-80V128h76.1L256 51.9zM336 464V176H232c-13.3 0-24-10.7-24-24V48H48v416h288z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tDesign Guideline\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tLogo placemant Size guide and best practise\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ccc836c elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"ccc836c\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-download\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M216 0h80c13.3 0 24 10.7 24 24v168h87.7c17.8 0 26.7 21.5 14.1 34.1L269.7 378.3c-7.5 7.5-19.8 7.5-27.3 0L90.1 226.1c-12.6-12.6-3.7-34.1 14.1-34.1H192V24c0-13.3 10.7-24 24-24zm296 376v112c0 13.3-10.7 24-24 24H24c-13.3 0-24-10.7-24-24V376c0-13.3 10.7-24 24-24h146.7l49 49c20.1 20.1 52.5 20.1 72.6 0l49-49H488c13.3 0 24 10.7 24 24zm-124 88c0-11-9-20-20-20s-20 9-20 20 9 20 20 20 20-9 20-20zm64 0c0-11-9-20-20-20s-20 9-20 20 9 20 20 20 20-9 20-20z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Download Free<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-b80dc35\" data-id=\"b80dc35\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-87db22e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"87db22e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-61ae76c\" data-id=\"61ae76c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-161d849 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"161d849\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1e6e675\" data-id=\"1e6e675\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-244dd88 elementor-widget elementor-widget-heading\" data-id=\"244dd88\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Let's Build Together<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-539f320 elementor-widget elementor-widget-heading\" data-id=\"539f320\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Frequently Asked Questions<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40b66c2 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"40b66c2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tThe finishing touches matter. Select the perfect back closure and add custom interior taping, woven labels, or hang tags for a retail-ready product.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94fd706 elementor-align-left elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"94fd706\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Free Digital Mockuups Included<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">No Hidden Fees And Costs<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Moldsje fasfnw sdfiw <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">DDP Shipping Available<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6c74bfa\" data-id=\"6c74bfa\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b30a68d elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"b30a68d\" data-element_type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\" aria-label=\"New Form\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"9315\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"b30a68d\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Custom Baseball Cap - JoinTop | Custom Hat Manufacturer &amp; Supplier | OEM &amp; ODM Headwear Factory\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"9315\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_6fe8ff3 elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_6fe8ff3\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tYour Name*\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_6fe8ff3]\" id=\"form-field-field_6fe8ff3\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Enter Your Name...\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-field_f5bc430 elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_f5bc430\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tEmail Address*\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[field_f5bc430]\" id=\"form-field-field_f5bc430\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Email...\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_8a286ec elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_8a286ec\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tEstamited Quantity*\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_8a286ec]\" id=\"form-field-field_8a286ec\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"e.g,500\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-select elementor-field-group elementor-column elementor-field-group-field_fa3ec34 elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_fa3ec34\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tCap Style\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field elementor-select-wrapper remove-before\">\n\t\t\t<div class=\"select-caret-down-wrapper\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-caret-down\" viewbox=\"0 0 571.4 571.4\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M571 393Q571 407 561 418L311 668Q300 679 286 679T261 668L11 418Q0 407 0 393T11 368 36 357H536Q550 357 561 368T571 393Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t<select name=\"form_fields[field_fa3ec34]\" id=\"form-field-field_fa3ec34\" class=\"elementor-field-textual elementor-size-sm\" required=\"required\">\n\t\t\t\t\t\t\t\t\t<option value=\"Select a style\">Select a style<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Baseball Caps\">Basebollkepsar<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Dad Caps\">Dad Caps<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Trucker Caps\">Trucker kepsar<\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tProduct Details*\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"4\" placeholder=\"Tell Us Your Product Color, Logo &amp; Details, Timeling ETC.\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-upload elementor-field-group elementor-column elementor-field-group-field_16bf236 elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_16bf236\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tUpload Design File (Optional)\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input type=\"file\" name=\"form_fields[field_16bf236]\" id=\"form-field-field_16bf236\" class=\"elementor-field elementor-size-sm  elementor-upload-field\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-paper-plane\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M440 6.5L24 246.4c-34.4 19.9-31.1 70.8 5.7 85.9L144 379.6V464c0 46.4 59.2 65.5 86.6 28.6l43.8-59.1 111.9 46.2c5.9 2.4 12.1 3.6 18.3 3.6 8.2 0 16.3-2.1 23.6-6.2 12.8-7.2 21.6-20 23.9-34.5l59.4-387.2c6.1-40.1-36.9-68.8-71.5-48.9zM192 464v-64.6l36.6 15.1L192 464zm212.6-28.7l-153.8-63.5L391 169.5c10.7-15.5-9.5-33.5-23.7-21.2L155.8 332.6 48 288 464 48l-59.4 387.3z\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Request Quote Now<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<input type=\"hidden\" name=\"trp-form-language\" value=\"sv\"\/><\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78f07eb elementor-widget elementor-widget-text-editor\" data-id=\"78f07eb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tWe respect your privacy, Your information never will be shared\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Premier Custom Baseball Cap Manufacturer OEM\/ODM Solutions for Brands, Wholesalers, and Corporate Promotions. Factory Direct Pricing with ISO9001 Quality Control. Get A Free Quote Download Catalog OEM\/ODM Expert 15+ years manufacturing experience. Factory Price Direct pricing, no middleman markup. 100% Custom Fully bespoke designs from scratch. Low MOQ Start small with 50pcs per style. Trusted [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"class_list":["post-9315","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.8.3.2 - aioseo.com -->\n\t<meta name=\"description\" content=\"MOQ: 100 pcs\/design Ripstop Fabric Velcro Patch Area Adjustable Fit\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"msvalidate.01\" content=\"8BA0B303B4E29CA9D056CBC45291BA73\" \/>\n\t<meta name=\"yandex-verification\" content=\"71ed0e0b2b153941\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/jointopcap.com\/sv\/product\/camo-tactical-cap\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.8.3.2\" \/>\n\t\t<meta property=\"og:locale\" content=\"sv_SE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"JoinTop | Custom Hat Manufacturer &amp; Supplier | OEM &amp; ODM Headwear Factory - JoinTop is a professional custom hat and cap manufacturer offering OEM &amp; ODM headwear solutions from China, Vietnam, and Bangladesh \u2014 trusted by global brands for quality and innovation.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Camo Tactical Cap - JoinTop | Custom Hat Manufacturer &amp; Supplier | OEM &amp; ODM Headwear Factory\" \/>\n\t\t<meta property=\"og:description\" content=\"MOQ: 100 pcs\/design Ripstop Fabric Velcro Patch Area Adjustable Fit\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/jointopcap.com\/sv\/product\/camo-tactical-cap\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/06\/cropped-2.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/06\/cropped-2.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-01-10T12:53:37+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-01-16T03:45:37+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Camo Tactical Cap - JoinTop | Custom Hat Manufacturer &amp; Supplier | OEM &amp; ODM Headwear Factory\" \/>\n\t\t<meta name=\"twitter:description\" content=\"MOQ: 100 pcs\/design Ripstop Fabric Velcro Patch Area Adjustable Fit\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/06\/cropped-2.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jointopcap.com\\\/sv\\\/product\\\/camo-tactical-cap\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/jointopcap.com\\\/sv#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jointopcap.com\\\/sv\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/jointopcap.com\\\/sv\\\/custom-baseball-cap\\\/#listItem\",\"name\":\"Custom Baseball Cap\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/jointopcap.com\\\/sv\\\/custom-baseball-cap\\\/#listItem\",\"position\":2,\"name\":\"Custom Baseball Cap\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/jointopcap.com\\\/sv#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jointopcap.com\\\/sv\\\/#organization\",\"name\":\"Jointop\",\"description\":\"JoinTop is a professional custom hat and cap manufacturer offering OEM & ODM headwear solutions from China, Vietnam, and Bangladesh \\u2014 trusted by global brands for quality and innovation.\",\"url\":\"https:\\\/\\\/jointopcap.com\\\/sv\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/jointopcap.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/cropped-2.png\",\"@id\":\"https:\\\/\\\/jointopcap.com\\\/sv\\\/product\\\/camo-tactical-cap\\\/#organizationLogo\",\"width\":667,\"height\":190},\"image\":{\"@id\":\"https:\\\/\\\/jointopcap.com\\\/sv\\\/product\\\/camo-tactical-cap\\\/#organizationLogo\"}},{\"@type\":\"Product\",\"@id\":\"https:\\\/\\\/jointopcap.com\\\/sv\\\/product\\\/camo-tactical-cap\\\/#product\",\"name\":\"Camo Tactical Cap\",\"url\":\"https:\\\/\\\/jointopcap.com\\\/sv\\\/product\\\/camo-tactical-cap\\\/\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/jointopcap.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/s-l960-4-1.webp\",\"width\":800,\"height\":800}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jointopcap.com\\\/sv\\\/product\\\/camo-tactical-cap\\\/#webpage\",\"url\":\"https:\\\/\\\/jointopcap.com\\\/sv\\\/product\\\/camo-tactical-cap\\\/\",\"name\":\"Camo Tactical Cap - JoinTop | Custom Hat Manufacturer & Supplier | OEM & ODM Headwear Factory\",\"description\":\"MOQ: 100 pcs\\\/design Ripstop Fabric Velcro Patch Area Adjustable Fit\",\"inLanguage\":\"sv-SE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jointopcap.com\\\/sv\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jointopcap.com\\\/sv\\\/product\\\/camo-tactical-cap\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/jointopcap.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/s-l960-4-1.webp\",\"@id\":\"https:\\\/\\\/jointopcap.com\\\/sv\\\/product\\\/camo-tactical-cap\\\/#mainImage\",\"width\":800,\"height\":800},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jointopcap.com\\\/sv\\\/product\\\/camo-tactical-cap\\\/#mainImage\"},\"datePublished\":\"2026-01-10T20:53:37+08:00\",\"dateModified\":\"2026-01-16T11:45:37+08:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jointopcap.com\\\/sv\\\/#website\",\"url\":\"https:\\\/\\\/jointopcap.com\\\/sv\\\/\",\"name\":\"JoinTop | Custom Hat Manufacturer & Supplier | OEM & ODM Headwear Factory\",\"description\":\"JoinTop is a professional custom hat and cap manufacturer offering OEM & ODM headwear solutions from China, Vietnam, and Bangladesh \\u2014 trusted by global brands for quality and innovation.\",\"inLanguage\":\"sv-SE\",\"publisher\":{\"@id\":\"https:\\\/\\\/jointopcap.com\\\/sv\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Camo Tactical Cap - JoinTop | Custom Hat Manufacturer &amp; Supplier | OEM &amp; ODM Headwear Factory<\/title>\n\n","aioseo_head_json":{"title":"Camo Tactical Cap - JoinTop | Custom Hat Manufacturer & Supplier | OEM & ODM Headwear Factory","description":"MOQ: 100 pcs\/design Ripstop Fabric Velcro Patch Area Adjustable Fit","canonical_url":"https:\/\/jointopcap.com\/sv\/product\/camo-tactical-cap\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"msvalidate.01":"8BA0B303B4E29CA9D056CBC45291BA73","yandex-verification":"71ed0e0b2b153941","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/jointopcap.com\/sv\/product\/camo-tactical-cap\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/jointopcap.com\/sv#listItem","position":1,"name":"Home","item":"https:\/\/jointopcap.com\/sv","nextItem":{"@type":"ListItem","@id":"https:\/\/jointopcap.com\/sv\/custom-baseball-cap\/#listItem","name":"Custom Baseball Cap"}},{"@type":"ListItem","@id":"https:\/\/jointopcap.com\/sv\/custom-baseball-cap\/#listItem","position":2,"name":"Custom Baseball Cap","previousItem":{"@type":"ListItem","@id":"https:\/\/jointopcap.com\/sv#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/jointopcap.com\/sv\/#organization","name":"Jointop","description":"JoinTop is a professional custom hat and cap manufacturer offering OEM & ODM headwear solutions from China, Vietnam, and Bangladesh \u2014 trusted by global brands for quality and innovation.","url":"https:\/\/jointopcap.com\/sv\/","logo":{"@type":"ImageObject","url":"https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/06\/cropped-2.png","@id":"https:\/\/jointopcap.com\/sv\/product\/camo-tactical-cap\/#organizationLogo","width":667,"height":190},"image":{"@id":"https:\/\/jointopcap.com\/sv\/product\/camo-tactical-cap\/#organizationLogo"}},{"@type":"Product","@id":"https:\/\/jointopcap.com\/sv\/product\/camo-tactical-cap\/#product","name":"Camo Tactical Cap","url":"https:\/\/jointopcap.com\/sv\/product\/camo-tactical-cap\/","image":{"@type":"ImageObject","url":"https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/s-l960-4-1.webp","width":800,"height":800}},{"@type":"WebPage","@id":"https:\/\/jointopcap.com\/sv\/product\/camo-tactical-cap\/#webpage","url":"https:\/\/jointopcap.com\/sv\/product\/camo-tactical-cap\/","name":"Camo Tactical Cap - JoinTop | Custom Hat Manufacturer & Supplier | OEM & ODM Headwear Factory","description":"MOQ: 100 pcs\/design Ripstop Fabric Velcro Patch Area Adjustable Fit","inLanguage":"sv-SE","isPartOf":{"@id":"https:\/\/jointopcap.com\/sv\/#website"},"breadcrumb":{"@id":"https:\/\/jointopcap.com\/sv\/product\/camo-tactical-cap\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/07\/s-l960-4-1.webp","@id":"https:\/\/jointopcap.com\/sv\/product\/camo-tactical-cap\/#mainImage","width":800,"height":800},"primaryImageOfPage":{"@id":"https:\/\/jointopcap.com\/sv\/product\/camo-tactical-cap\/#mainImage"},"datePublished":"2026-01-10T20:53:37+08:00","dateModified":"2026-01-16T11:45:37+08:00"},{"@type":"WebSite","@id":"https:\/\/jointopcap.com\/sv\/#website","url":"https:\/\/jointopcap.com\/sv\/","name":"JoinTop | Custom Hat Manufacturer & Supplier | OEM & ODM Headwear Factory","description":"JoinTop is a professional custom hat and cap manufacturer offering OEM & ODM headwear solutions from China, Vietnam, and Bangladesh \u2014 trusted by global brands for quality and innovation.","inLanguage":"sv-SE","publisher":{"@id":"https:\/\/jointopcap.com\/sv\/#organization"}}]},"og:locale":"sv_SE","og:site_name":"JoinTop | Custom Hat Manufacturer &amp; Supplier | OEM &amp; ODM Headwear Factory - JoinTop is a professional custom hat and cap manufacturer offering OEM &amp; ODM headwear solutions from China, Vietnam, and Bangladesh \u2014 trusted by global brands for quality and innovation.","og:type":"article","og:title":"Camo Tactical Cap - JoinTop | Custom Hat Manufacturer &amp; Supplier | OEM &amp; ODM Headwear Factory","og:description":"MOQ: 100 pcs\/design Ripstop Fabric Velcro Patch Area Adjustable Fit","og:url":"https:\/\/jointopcap.com\/sv\/product\/camo-tactical-cap\/","og:image":"https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/06\/cropped-2.png","og:image:secure_url":"https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/06\/cropped-2.png","article:published_time":"2026-01-10T12:53:37+00:00","article:modified_time":"2026-01-16T03:45:37+00:00","twitter:card":"summary_large_image","twitter:title":"Camo Tactical Cap - JoinTop | Custom Hat Manufacturer &amp; Supplier | OEM &amp; ODM Headwear Factory","twitter:description":"MOQ: 100 pcs\/design Ripstop Fabric Velcro Patch Area Adjustable Fit","twitter:image":"https:\/\/jointopcap.com\/wp-content\/uploads\/2024\/06\/cropped-2.png"},"aioseo_meta_data":{"post_id":"9315","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":"0","ai":null,"created":"2026-01-10 06:35:48","updated":"2026-03-11 01:19:45"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/jointopcap.com\/sv\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\tCustom Baseball Cap\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/jointopcap.com\/sv"},{"label":"Custom Baseball Cap","link":"https:\/\/jointopcap.com\/sv\/custom-baseball-cap\/"}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/jointopcap.com\/sv\/wp-json\/wp\/v2\/pages\/9315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jointopcap.com\/sv\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/jointopcap.com\/sv\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/jointopcap.com\/sv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jointopcap.com\/sv\/wp-json\/wp\/v2\/comments?post=9315"}],"version-history":[{"count":1680,"href":"https:\/\/jointopcap.com\/sv\/wp-json\/wp\/v2\/pages\/9315\/revisions"}],"predecessor-version":[{"id":12149,"href":"https:\/\/jointopcap.com\/sv\/wp-json\/wp\/v2\/pages\/9315\/revisions\/12149"}],"wp:attachment":[{"href":"https:\/\/jointopcap.com\/sv\/wp-json\/wp\/v2\/media?parent=9315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}